{"id":187587,"date":"2025-07-04T12:44:56","date_gmt":"2025-07-04T18:44:56","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=187587"},"modified":"2025-07-04T12:44:58","modified_gmt":"2025-07-04T18:44:58","slug":"rosalba-hernandez-sera-presidenta-del-tsj-de-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/07\/04\/rosalba-hernandez-sera-presidenta-del-tsj-de-veracruz\/","title":{"rendered":"Rosalba Hern\u00e1ndez ser\u00e1 presidenta del TSJ de Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sam Ojeda \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa.- El Organismo P\u00fablico Local Electoral (OPLE) design\u00f3 a la magistrada Rosalba Hern\u00e1ndez Hern\u00e1ndez como pr\u00f3xima presidenta del Tribunal Superior de Justicia del Estado de Veracruz (TSJEV), decisi\u00f3n que entrar\u00e1 en vigor el 1 de septiembre y tendr\u00e1 una duraci\u00f3n de dos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque Luz Mar\u00eda L\u00f3pez Aburto fue la candidata m\u00e1s votada en el proceso electoral extraordinario 2024-2025, con m\u00e1s de 664 mil sufragios, su elecci\u00f3n fue para el Tribunal de Conciliaci\u00f3n y Arbitraje (TCA), lo que la excluye del Pleno del TSJEV y, por tanto, de la posibilidad de presidirlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el acuerdo OPLEV\/CG293\/2025, aprobado en sesi\u00f3n especial, el Consejo General del OPLE consider\u00f3 que el art\u00edculo octavo transitorio de la reforma a la Constituci\u00f3n de Veracruz establece que la presidencia del TSJEV ser\u00e1 ocupada, de manera excepcional, por la persona que haya obtenido el mayor n\u00famero de votos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tratarse de \u00f3rganos distintos dentro del Poder Judicial, se resolvi\u00f3 que este criterio solo aplica entre quienes fueron electos para el Tribunal Superior de Justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo ese razonamiento, el \u00f3rgano electoral reconoci\u00f3 que la segunda persona m\u00e1s votada, Rosalba Hern\u00e1ndez Hern\u00e1ndez, quien obtuvo 276 mil 926 votos y fue electa como magistrada del TSJEV, re\u00fane los requisitos para encabezar la presidencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n del OPLE se da en un contexto in\u00e9dito, pues es la primera vez que en Veracruz las magistraturas del Poder Judicial se eligen mediante voto ciudadano. Este vac\u00edo de antecedentes ha provocado interpretaciones distintas sobre el alcance de la reforma constitucional y qui\u00e9n debe ocupar la presidencia del tribunal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo puede ser impugnado ante las instancias electorales. Las candidaturas que consideren que hubo irregularidades en el proceso tienen hasta el 4 de julio para presentar recursos legales ante el propio OPLE, el Tribunal Electoral de Veracruz, la Sala Regional Xalapa o la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sam Ojeda \/ NV Noticias Xalapa.- El Organismo P\u00fablico Local Electoral (OPLE) design\u00f3 a la magistrada Rosalba Hern\u00e1ndez Hern\u00e1ndez como pr\u00f3xima presidenta del Tribunal Superior de Justicia del Estado de Veracruz (TSJEV), decisi\u00f3n que entrar\u00e1 en vigor el 1 de septiembre y tendr\u00e1 una duraci\u00f3n de dos a\u00f1os. Aunque Luz Mar\u00eda L\u00f3pez Aburto fue la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":44866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[1282],"class_list":["post-187587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-tribunal-superior-de-justicia","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=187587"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187587\/revisions"}],"predecessor-version":[{"id":187588,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187587\/revisions\/187588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/44866"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=187587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=187587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=187587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}