{"id":187403,"date":"2025-07-03T12:13:47","date_gmt":"2025-07-03T18:13:47","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=187403"},"modified":"2025-07-03T12:13:49","modified_gmt":"2025-07-03T18:13:49","slug":"advierte-ceapp-uso-excesivo-de-denuncias-contra-periodistas-por-violencia-politica","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/07\/03\/advierte-ceapp-uso-excesivo-de-denuncias-contra-periodistas-por-violencia-politica\/","title":{"rendered":"Advierte CEAPP uso excesivo de denuncias contra periodistas por violencia pol\u00edtica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sam Ojeda \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa.- Las denuncias contra periodistas por supuestos actos de violencia pol\u00edtica en raz\u00f3n de g\u00e9nero han ido en aumento en Veracruz, situaci\u00f3n que podr\u00eda derivar en un intento por frenar el ejercicio cr\u00edtico de la prensa, alert\u00f3 el presidente de la Comisi\u00f3n Estatal para la Atenci\u00f3n y Protecci\u00f3n de los Periodistas (CEAPP), Luis Ram\u00edrez Baqueiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comisionado destac\u00f3 que en un solo expediente se ha involucrado a nueve periodistas, lo que \u2014dijo\u2014 evidencia un uso indiscriminado de esta figura legal. Afirm\u00f3 que la problem\u00e1tica no parte de los mecanismos de protecci\u00f3n, sino de la actuaci\u00f3n de jueces y autoridades electorales, quienes deber\u00edan aplicar criterios m\u00e1s rigurosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo preocupante es que cualquier juzgador, por buscar favores o mantener cercan\u00eda con la persona denunciante, acepta sin filtros cualquier se\u00f1alamiento\u201d, advirti\u00f3. Para Ram\u00edrez Baqueiro, los jueces deber\u00edan negar las denuncias que no se sostienen legalmente, especialmente si lo que se cuestiona es la funci\u00f3n p\u00fablica de alguien se\u00f1alado por presunto cacicazgo o irregularidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 que la falta de criterios firmes permite que actores pol\u00edticos usen la figura de violencia pol\u00edtica de g\u00e9nero como herramienta para inhibir la cr\u00edtica, incluso cuando esta proviene de reportajes o columnas con sustento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, cuestion\u00f3 la postura de experiodistas que hoy se desempe\u00f1an en cargos p\u00fablicos y que, lejos de defender la libertad de expresi\u00f3n, han optado por utilizar mecanismos jur\u00eddicos para silenciar a sus antiguos colegas. \u201cResulta lamentable que haya quienes olviden su paso por los medios y ahora pretendan desactivar voces inc\u00f3modas escud\u00e1ndose en una figura que deber\u00eda proteger, no censurar\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ram\u00edrez Baqueiro tambi\u00e9n hizo un llamado al Congreso local para establecer reglas claras que delimiten cu\u00e1ndo procede una denuncia por violencia pol\u00edtica, y urgi\u00f3 a la autoridad electoral a emitir lineamientos m\u00e1s precisos y sensibles ante el contexto del trabajo period\u00edstico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa responsabilidad tambi\u00e9n recae en quienes hacen las leyes. Hay un desconocimiento profundo del tema y eso facilita que cualquiera pueda presentar una queja, sin que se analice si est\u00e1 fundamentada o no\u201d, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese al panorama, el titular de la CEAPP reiter\u00f3 el compromiso del organismo con la defensa del ejercicio period\u00edstico. \u201cNosotros no avalamos que se intente callar a la prensa cr\u00edtica. Informar y se\u00f1alar lo que ocurre en el servicio p\u00fablico es parte de nuestra funci\u00f3n social\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sam Ojeda \/ NV Noticias Xalapa.- Las denuncias contra periodistas por supuestos actos de violencia pol\u00edtica en raz\u00f3n de g\u00e9nero han ido en aumento en Veracruz, situaci\u00f3n que podr\u00eda derivar en un intento por frenar el ejercicio cr\u00edtico de la prensa, alert\u00f3 el presidente de la Comisi\u00f3n Estatal para la Atenci\u00f3n y Protecci\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":142059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[456,457],"class_list":["post-187403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-ceapp","tag-periodistas","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=187403"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187403\/revisions"}],"predecessor-version":[{"id":187404,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/187403\/revisions\/187404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/142059"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=187403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=187403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=187403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}