{"id":185797,"date":"2025-06-13T08:53:54","date_gmt":"2025-06-13T14:53:54","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=185797"},"modified":"2025-06-13T08:53:55","modified_gmt":"2025-06-13T14:53:55","slug":"2027-y-la-decision-de-los-alcaldes-de-oposicion-en-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/06\/13\/2027-y-la-decision-de-los-alcaldes-de-oposicion-en-veracruz\/","title":{"rendered":"2027 y la decisi\u00f3n de los alcaldes de oposici\u00f3n en Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong>Ricardo Chua<\/strong><\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mucho se est\u00e1 comentando en Veracruz, que despu\u00e9s de que la gobernadora Roc\u00edo Nahle Garc\u00eda, junto con el partido MORENA, &#8220;pint\u00f3 su raya&#8221; con los alcaldes electos de Movimiento Ciudadano, con su dirigencia nacional y estatal del organismo, luego del proceso municipal del 1 de junio, cuando d\u00edas posteriores a la elecci\u00f3n se\u00f1al\u00f3 que MC postul\u00f3 a varios candidatos, que est\u00e1n ligados a grupos fuera de la ley que operan en Veracruz.. Qued\u00f3 asentado, entonces, que estos presidentes municipales electos, no ser\u00e1n convencidos por su gobierno, ni por la dirigencia de MORENA, a pasarse a sus filas y afiliarse a su partido..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ello, MORENA pierde la oportunidad de acrecentar el n\u00famero de alcaldes.. Ya que MC queda como la segunda fuerza electoral en el Estado con el mayor n\u00famero de alcald\u00edas, despu\u00e9s de la coalici\u00f3n MORENA-PVEM.. Ahora s\u00f3lo habr\u00e1 que ver si el resto de la oposici\u00f3n, como el PRI o PAN, sus alcaldes electos, no son &#8220;convencidos&#8221; por MORENA para que ellos sean los que caigan con el &#8220;canto de las sirenas&#8221;.. Sabiendo que el partido &#8220;guinda&#8221; sigue con ese rol agresivo y nada pol\u00edtico con partidos que no son de la 4T.. Si a los suyos los maltrata, vean el ejemplo del PVEM o PT, que mejor la &#8220;jug\u00f3&#8221; solo.. Que se pueden esperar m\u00e1s adelante, si se van para all\u00e1..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se comenta que ya muchos alcaldes electos de oposici\u00f3n, que ten\u00edan la intenci\u00f3n de irse a MORENA, antes de diciembre, para ser parte de la 4T, ahora lo est\u00e1n pensando mejor.. Est\u00e1n viendo en qui\u00e9n conf\u00edan m\u00e1s y sobre todo, lo que les est\u00e1n ofreciendo en sus partidos donde ganaron la alcald\u00eda.. Saben que sacan mejor provecho siendo oposici\u00f3n, que estando dentro de la 4T.. Tendr\u00e1n que negociar con ellos para lograr acuerdos y como alcaldes estar\u00e1n dos a\u00f1os m\u00e1s cuando el Congreso Local, se renueve en 2027.. Ah\u00ed est\u00e1 el detalle.. Los mun\u00edcipes electos que sean estrategas, van a esperar a esas elecciones intermedias para ver que pierde o gana MORENA.. Finalmente tendr\u00e1n tiempo para el &#8220;arrepentimiento&#8221; o la &#8220;estocada&#8221; final.. EL QUE ENTENDI\u00d3, LO ENTENDI\u00d3..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">XALAPA Y COATZACOALCOS, EL RIESGO DE MORENA EN 2027.. Despu\u00e9s de las elecciones a las alcald\u00edas en los 212 municipios de Veracruz, el pasado 1 de junio, y que dej\u00f3 como resultado una DEBACLE electoral para MORENA en toda la entidad.. Ese partido, sus dirigentes y pol\u00edticos afines a ese organismos.. Han estado mencionado en redes sociales y medios de comunicaci\u00f3n, que hab\u00edan logrado &#8220;GRANDES&#8221; triunfos en municipios importantes como Xalapa y Coatzacoalcos, que ahora eran sus &#8220;bastiones&#8221;, para minimizar los casos Perote, Orizaba, Cosoleacaque, Poza Rica, Papantla y otros ayuntamientos m\u00e1s.. Pero en el caso concreto de Xalapa y Coatzacoalcos, el triunfo de MORENA, no se lo debe a su militancia.. Se lo debe al PRI..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed como lo leen.. Esas &#8220;victorias&#8221; que tanto publicita MORENA como unos triunfos que &#8220;consolidan&#8221; su fuerza real en el centro y sureste de Veracruz.. Es un &#8220;espejismo&#8221; que en pol\u00edtica, siempre suelen ser peligrosos y tr\u00e1gicos para el partido en el poder.. Ya que la REALIDAD de que MORENA haya ganado esos dos ayuntamientos, se debe principalmente porque esas elecciones se fueron a &#8220;TERCIOS&#8221;.. De no haber sido as\u00ed, en este momento, MORENA estar\u00eda &#8220;llorando&#8221; dos &#8220;descalabros&#8221; fundamentales para la 4T y seguramente Movimiento Ciudadano, estar\u00eda sumando 44 ayuntamientos en su poder.. Ya que el tema Papantla a\u00fan est\u00e1 en tribunales..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La explicaci\u00f3n de todo esto, es muy sencilla: El PRI en Xalapa lanz\u00f3 un candidato que creci\u00f3 en demas\u00eda como fue Silvio Lagos Galindo.. Qu\u00e9 pese a todo lo que dijeron de \u00e9l, este se ech\u00f3 el partido a las espaldas y una candidatura que nadie quer\u00eda en la capital por el priismo.. Dio la batalla y fue un rival digno de la 4T.. En Coatzacoalcos pas\u00f3 lo mismo.. Carlos Vasconcelos logr\u00f3 crecer y hacer crecer electoralmente al PRI, que en ese municipio hab\u00eda sido &#8220;arrasado&#8221; por MORENA un a\u00f1o antes.. Logr\u00f3 levantar los votos a favor del PRI y ahora tendr\u00e1 m\u00e1s regidores, que en el actual cuatrienio en aquella ciudad.. Y eso provoc\u00f3 el triunfo de MORENA..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya que al lanzar candidatos, que se volvieron competitivos, el PRI se qued\u00f3 con los votos y logr\u00f3 m\u00e1s por la aceptaci\u00f3n ciudadana.. Que de no haber sido as\u00ed o con otros candidatos de menor &#8220;calibre&#8221;, esos votos se hubieran ido para Movimiento Ciudadano.. Esos eran votos que NO LOS IBA A TENER MORENA.. Esos votos del PRI y MC, no iban a ir a parar en las boletas a favor de Daniela Griego, en Xalapa y Pedro Miguel Rosaldo, en Coatzacoalcos.. Y como se dieron los n\u00fameros, sin una elecci\u00f3n de tercios como se present\u00f3 en estos dos sitios, los triunfos hubieran sido para Movimiento Ciudadano, no para MORENA.. Si suman los votos del PRI y MC en estos dos ayuntamientos, se dar\u00e1n cuenta que son m\u00e1s de los que obtuvo MORENA.. REAL POLITIK..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">REFLEXI\u00d3N.. Escenarios pol\u00edticos como el de Xalapa y Coatzacoalcos hay varios en la entidad.. El problema es que son cabeceras municipales y de distrito.. Lo cual ha &#8220;encendido&#8221; las &#8220;alarmas&#8221; en Palacio de Gobierno en Xalapa y en el partido MORENA.. Porque por m\u00e1s que digan que ganaron 80 municipios en coalici\u00f3n con PVEM.. Los que manejan MORENA en Veracruz saben, que tienen en riesgo la elecci\u00f3n del 2027.. Y que son 15 distritos en color &#8220;rojo&#8221;, que de perderlos, ya no tendr\u00e1n el CONTROL del Congreso Local.. Y eso pone en riesgo a MORENA en Veracruz para las elecciones municipales del 2029 y la sucesi\u00f3n estatal del 2030.. Y eso que acaba de pasar la elecci\u00f3n del 2025.. AS\u00cd DE GRAVE EL PANORAMA..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OJO.. En este mismo espacio, hace unas semanas, se\u00f1alamos que a diferencia de los meses de enero o febrero, que se dec\u00eda que MORENA podr\u00eda ganar hasta 190 ayuntamientos en Veracruz en las elecciones municipales.. En abril y mayo mencionamos, que por todos los problemas surgidos en la selecci\u00f3n de candidatos de alcaldes y por los conflictos al interior, MORENA podr\u00eda tener una DEBACLE y s\u00f3lo ganar de 120 a 130 municipios.. Y saben qu\u00e9, nos equivocamos, nos quedamos cortos, se perdieron entre 40 a 50 municipios m\u00e1s.. A pesar de las mentadas y recordatorios familiares en redes sociales.. Se quedaron con 80 en coalici\u00f3n y 11 m\u00e1s como partido &#8220;jugando&#8221; solos.. Los n\u00fameros no mienten.. MC s\u00ed creci\u00f3 y le quit\u00f3 votos a MORENA.. CONSUMATUM EST..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Chua Mucho se est\u00e1 comentando en Veracruz, que despu\u00e9s de que la gobernadora Roc\u00edo Nahle Garc\u00eda, junto con el partido MORENA, &#8220;pint\u00f3 su raya&#8221; con los alcaldes electos de Movimiento Ciudadano, con su dirigencia nacional y estatal del organismo, luego del proceso municipal del 1 de junio, cuando d\u00edas posteriores a la elecci\u00f3n se\u00f1al\u00f3 [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":185798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[245],"tags":[327],"class_list":["post-185797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dialogos-de-poder","tag-ricardo-chua","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/185797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=185797"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/185797\/revisions"}],"predecessor-version":[{"id":185799,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/185797\/revisions\/185799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/185798"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=185797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=185797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=185797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}