{"id":177406,"date":"2025-03-27T09:51:12","date_gmt":"2025-03-27T15:51:12","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=177406"},"modified":"2025-03-27T09:51:14","modified_gmt":"2025-03-27T15:51:14","slug":"delegados-federales-deben-apoyar-el-trabajo-de-nahle","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/03\/27\/delegados-federales-deben-apoyar-el-trabajo-de-nahle\/","title":{"rendered":"Delegados federales deben apoyar el trabajo de Nahle"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jos\u00e9 Luis Enr\u00edquez Ambell<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ahora bien llamadas representaciones del gobierno de la rep\u00fablica con sede en cada estado del pa\u00eds &#8211; antes delegaciones federales &#8211; son oficinas de gesti\u00f3n, acciones, obras y servicios, y que para la Secretaria de Hacienda y Cr\u00e9dito P\u00fablico (SHCP), significan unidades administrativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con presupuesto y personalidad jur\u00eddica se encargan de atender las problem\u00e1ticas de su competencia en cada entidad federativa, pero se coordinan con el gobierno del estado &#8211; en este caso con Veracruz y Roc\u00edo Nahle &#8211; y de manera conjunta buscar el impulso de los planes y programas de acuerdo al \u00e1mbito de su competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace unas horas vimos como el sector de la Secretar\u00eda de Infraestructura, Comunicaciones y Transportes (SICT) se reuni\u00f3 con la Ingeniera Roc\u00edo Nahle y gabinete correspondiente, para revisar, evaluar y realizar obras de inter\u00e9s para Veracruz en t\u00e9rminos de la red carretera en su conjunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habr\u00eda de suponer, que el equipo de trabajo cercano a la Gobernadora, le estar\u00edan por sugerir similares acciones con otros sectores del gobierno federal en territorio veracruzano como el de salud, hidr\u00e1ulico, medio ambiente, agrario, entre otros m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gabinete legal y ampliado de Nahle, as\u00ed lo pienso y creo, sabe que el desarrollo en su conjunto necesita del esfuerzo de muchos y cada vez m\u00e1s actores oficiales y privados, pues rescatar a Veracruz y ponerlo de moda es una din\u00e1mica que requiere sumar voluntades, pero tambi\u00e9n presupuestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tengo la impresi\u00f3n que en los d\u00edas por venir, los titulares de las oficinas federales con sede en Veracruz, de no concatenar su esfuerzo y m\u00edstica con la din\u00e1mica del gobierno estatal, en algunos casos, podr\u00edan tener que dejar sus espacios para que vengan sus relevos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DE SOBREMESA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular del Poder Ejecutivo en Veracruz, sabe bien de la importancia que juegan todos esos espacios (m\u00e1s de cincuenta) del gobierno federal en nuestro estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y tambi\u00e9n sabe que, en cada oficina de representaci\u00f3n del Gobierno de la Rep\u00fablica recae en perfiles espec\u00edficos para lo que necesita construir en Veracruz junto a la Dra. Claudia Sheinbaum, Presidenta de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ellas son quienes acuerdan quienes deben y pueden ocupar las representaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">UN CAF\u00c9 LECHERO LIGHT<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada delegaci\u00f3n o coordinaci\u00f3n o como les llamen, sostienen un rol de importancia social y pol\u00edtica que facilita mucho la atenci\u00f3n directa e indirecta con la poblaci\u00f3n en su conjunto y mucho m\u00e1s con el universo de todos los derechohabientes, en el caso del sector salud a trav\u00e9s del ISSSTE e IMSS (Norte y Sur), e incluso se habla de pr\u00f3ximos ajustes en esas \u00e1reas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">UN CAF\u00c9 CON PILONCILLO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo hace suponer que durante este primer semestre del 2025 se dar\u00e1n cambios y quiz\u00e1 enroques en las estructuras delegacionales, en medio de la efervescente \u00e9poca de pr\u00f3ximas elecciones de ayuntamientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">UN CAF\u00c9 CON PIQUETE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Pero que nadie se mueva, pues quien usar\u00e1 el l\u00e1piz y borrador para todos los cargos en ese terreno Veracruzano habr\u00e1 de ser s\u00f3lo la Ing. Roc\u00edo Nahle y sin intermediarios ante la Dra. Claudia Sheinbaum&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1ES CUANTO!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">enriquezambell@gmail.com;<br>enamjl62@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Luis Enr\u00edquez Ambell Las ahora bien llamadas representaciones del gobierno de la rep\u00fablica con sede en cada estado del pa\u00eds &#8211; antes delegaciones federales &#8211; son oficinas de gesti\u00f3n, acciones, obras y servicios, y que para la Secretaria de Hacienda y Cr\u00e9dito P\u00fablico (SHCP), significan unidades administrativas. Con presupuesto y personalidad jur\u00eddica se encargan [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":161859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[18007],"tags":[],"class_list":["post-177406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafe-de-manana","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/177406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=177406"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/177406\/revisions"}],"predecessor-version":[{"id":177407,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/177406\/revisions\/177407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/161859"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=177406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=177406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=177406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}