{"id":175984,"date":"2025-03-13T09:38:03","date_gmt":"2025-03-13T15:38:03","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=175984"},"modified":"2025-03-13T09:38:05","modified_gmt":"2025-03-13T15:38:05","slug":"por-ahora-no-impondremos-aranceles-reciprocos-sheinbaum","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/03\/13\/por-ahora-no-impondremos-aranceles-reciprocos-sheinbaum\/","title":{"rendered":"Por ahora no impondremos aranceles rec\u00edprocos: Sheinbaum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En una guerra comercial nadie gana, sostuvo la presidenta Claudia Sheinbaum por eso por ahora no se van a adoptar decisiones de imponer aranceles rec\u00edprocos a los productos estadunidenses que llegan a M\u00e9xico. Anunci\u00f3 que a diferencia de otros pa\u00edses donde han comenzado a adoptar medidas similares con las mercanc\u00edas de Estados Unidos, en M\u00e9xico se mantiene una negociaci\u00f3n para vetarlos y se esperar\u00e1 hasta el 2 de abril, cuando Estados Unidos formalice el marco comercial que regir\u00e1 sus intercambios, cuando se determinen medidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos trabajando en reuniones muy cotidianas, algunas son telef\u00f3nicas otras presenciales, con el gobierno de Estados Unidos al m\u00e1s alto nivel para tener una condici\u00f3n donde realmente haya reciprocidad el 2 de abril.Si tu me aplicas aranceles, yo te aplico aranceles. A partir del anuncio tomaremos nuestras decisiones. No tiene caso anunciar una y otra medida, no tiene caso hacerlo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheinbaum afirm\u00f3 que existen muchos estudios que demuestran que \u201cla inversi\u00f3n en M\u00e9xico de una empresa estadounidense genera el triple de empleos en Estado Unidos por la integraci\u00f3n econ\u00f3mica de ambos pa\u00edses , porque no se produce todo un coche en M\u00e9xico sino parcialmente en M\u00e9xico y Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el secretario de Econom\u00eda, Ebrard dijo que el principal impacto que tendr\u00e1 la imposici\u00f3n general aranceles de Estados Unidos son los precios al consumidor en ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que el argumento central que se tiene en Estados Unidos es que con los aranceles se va a iniciar una proceso de relocalizaci\u00f3n de empresas que se trasladar\u00edan a Estados Unidos,sin embargo, las experiencias que se han tenido en el pasado es que los aranceles no se han traducido en el traslado de empresas a territorio estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, resalt\u00f3 que el portafolio de inversiones en M\u00e9xico que se proyectan para este sexenio suman 220 mil millones de d\u00f3lares de los cuales 60 por ciento provienen de empresas nacionales y 40 por ciento es inversi\u00f3n extranjera. Lo importante hasta ahora, dijo el secretario, es que hasta el momento,en esta coyuntura no se han recibido notificaci\u00f3n de cancelaciones de inversiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas medidas para reducir el d\u00e9ficit comercial de Estados Unidos&nbsp; es eso, pero el costo es el aumento de los precios, dificultades para el uso cotidiano. Cuando se compra un electrodom\u00e9stico un autom\u00f3vil va a subir el precio. Va a ser m\u00e1s caro\u201d, dijo Ebrard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, Sheinbaum asever\u00f3 que una empresa sider\u00fargica no se traslada de un d\u00eda para otro, en autom\u00f3viles o de otras empresas sider\u00fargicas. EN el caso de M\u00e9xico, en acero y aluminio el balance comercial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al abundar sobre el tema, Sheinbaum dijo\u00a0que \u201clo que nos conviene es seguir con el tratado comercial y revisarlo que deba revisarse hacer pero competir con el resto del mundo como regi\u00f3n y consolidarla para competir con otras zonas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2025\/03\/13\/politica\/por-ahora-no-impondremos-aranceles-reciprocos-a-eu-en-guerra-comercial-nadie-gana-sheinbaum\">Jornada<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una guerra comercial nadie gana, sostuvo la presidenta Claudia Sheinbaum por eso por ahora no se van a adoptar decisiones de imponer aranceles rec\u00edprocos a los productos estadunidenses que llegan a M\u00e9xico. Anunci\u00f3 que a diferencia de otros pa\u00edses donde han comenzado a adoptar medidas similares con las mercanc\u00edas de Estados Unidos, en M\u00e9xico [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":175143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,183,292,162],"class_list":["post-175984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-estados-unidos","tag-mexico","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/175984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=175984"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/175984\/revisions"}],"predecessor-version":[{"id":175989,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/175984\/revisions\/175989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/175143"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=175984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=175984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=175984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}