{"id":173947,"date":"2025-02-21T09:20:11","date_gmt":"2025-02-21T15:20:11","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=173947"},"modified":"2025-02-21T09:20:13","modified_gmt":"2025-02-21T15:20:13","slug":"presidenta-envia-iniciativa-contra-toda-injerencia-extranjera","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/02\/21\/presidenta-envia-iniciativa-contra-toda-injerencia-extranjera\/","title":{"rendered":"Presidenta env\u00eda iniciativa contra toda injerencia extranjera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum envi\u00f3 ayer al Congreso de la Uni\u00f3n una iniciativa de reforma a los art\u00edculos 19 y 40 de la Constituci\u00f3n en materia de fortalecimiento de la soberan\u00eda nacional y para introducir el delito de terrorismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta sigue a la decisi\u00f3n del gobierno de Estados Unidos de designar como organizaciones terroristas globales a seis grupos del crimen organizado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo es dejar claro, afirm\u00f3 la mandataria en su conferencia del jueves, que con cualquier pa\u00eds, y sobre todo con el vecino del norte,&nbsp;<q>colaboramos, nos coordinamos, trabajamos juntos<\/q>, pero sin injerencismo ni violaci\u00f3n a la soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la iniciativa, que ayer por la tarde lleg\u00f3 al Senado, Sheinbaum plantea agregar dos p\u00e1rrafos al art\u00edculo 40 constitucional, para que diga: \u201cEl pueblo de M\u00e9xico bajo ninguna circunstancia aceptar\u00e1 intervenciones, intromisiones o cualquier otro acto desde el extranjero que sea lesivo de la integridad, independencia y soberan\u00eda de la naci\u00f3n, tales como golpes de Estado, injerencia en elecciones o la violaci\u00f3n del territorio mexicano, sea \u00e9sta por tierra, mar o espacio a\u00e9reo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><q>Tampoco consentir\u00e1 intervenci\u00f3n en investigaci\u00f3n y persecuci\u00f3n alguna, sin la autorizaci\u00f3n y colaboraci\u00f3n expresa del Estado mexicano en el marco de las leyes aplicables<\/q>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria tambi\u00e9n propone modificar el art\u00edculo 19 para incluir el delito de terrorismo, t\u00e9rmino que no fue mencionado por la titular del Ejecutivo en la conferencia, pero que aparece en el documento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2025\/02\/21\/politica\/presidenta-envia-iniciativa-contra-toda-injerencia-extranjera-3573\">Jornada<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum envi\u00f3 ayer al Congreso de la Uni\u00f3n una iniciativa de reforma a los art\u00edculos 19 y 40 de la Constituci\u00f3n en materia de fortalecimiento de la soberan\u00eda nacional y para introducir el delito de terrorismo. La propuesta sigue a la decisi\u00f3n del gobierno de Estados Unidos de designar como organizaciones terroristas [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":173951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[2801,162],"class_list":["post-173947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-claudia-sheinbaum","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=173947"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173947\/revisions"}],"predecessor-version":[{"id":173952,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173947\/revisions\/173952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/173951"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=173947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=173947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=173947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}