{"id":173848,"date":"2025-02-20T10:29:27","date_gmt":"2025-02-20T16:29:27","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=173848"},"modified":"2025-02-20T10:29:29","modified_gmt":"2025-02-20T16:29:29","slug":"sheinbaum-envia-al-congreso-iniciativa-sobre-soberania-e-injerencismo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/02\/20\/sheinbaum-envia-al-congreso-iniciativa-sobre-soberania-e-injerencismo\/","title":{"rendered":"Sheinbaum env\u00eda al Congreso iniciativa sobre soberan\u00eda e injerencismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum env\u00eda hoy al Congreso de la Uni\u00f3n una iniciativa de reforma de los art\u00edculos 19 y 40 constitucional, con el objetivo de dejar claro que con cualquier pa\u00eds y en particular con Estados Unidos \u201ccolaboramos, nos coordinamos, trabajamos juntos\u201d, pero sin injerencismo ni violaci\u00f3n a la soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQueremos que eso quede claro\u201d, enfatiz\u00f3 la mandataria, una vez que el gobierno y el Senado de Estados Unidos decidieron denominar grupos terroristas a seis grupos del crimen organizado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, el art\u00edculo 40 incorpora que el pueblo de M\u00e9xico, \u201cbajo ninguna circunstancia aceptar\u00e1 intervenciones, intromisiones\u201d o cualquier actividad que provenga del extranjero y sea lesivo de la soberan\u00eda nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que no se aceptar\u00e1 ning\u00fan tipo de incursi\u00f3n por tierra, agua o el espacio a\u00e9reo, ni se consentir\u00e1 la realizaci\u00f3n de investigaciones o persecuciones sin la aprobaci\u00f3n expresa del Estado mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, la propuesta de reforma al art\u00edculo 19 constitucional plantea que cualquier nacional o extranjero involucrado en la fabricaci\u00f3n, distribuci\u00f3n, traslado en el territorio nacional de armas, as\u00ed como cualquier extranjero que realice actividades al margen de la ley, \u201cse le impondr\u00e1 la pena m\u00e1s severa posible\u201d y ser\u00e1 sujeto de la prisi\u00f3n preventiva oficiosa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheinbaum inform\u00f3 que tambi\u00e9n por la decisi\u00f3n anunciada ayer por el gobierno estadunidense y el reconocimiento del Departamento de Justicia de que 74 por ciento de las armas incautadas provienen de ese pa\u00eds, la Secretar\u00eda de Relaciones Exteriores est\u00e1 trabajando en torno a la demanda de M\u00e9xico contra las productoras y distribuidoras de armas, a fin ampliarla e incluir como responsables por complicidad a aquellos que vendan armas que son introducidas a territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2025\/02\/20\/politica\/sheinbaum-envia-al-congreso-iniciativa-sobre-soberania-e-injerencismo-1207\">Jornada<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum env\u00eda hoy al Congreso de la Uni\u00f3n una iniciativa de reforma de los art\u00edculos 19 y 40 constitucional, con el objetivo de dejar claro que con cualquier pa\u00eds y en particular con Estados Unidos \u201ccolaboramos, nos coordinamos, trabajamos juntos\u201d, pero sin injerencismo ni violaci\u00f3n a la soberan\u00eda. \u201cQueremos que eso quede [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":23864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,162],"class_list":["post-173848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=173848"}],"version-history":[{"count":5,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173848\/revisions"}],"predecessor-version":[{"id":173853,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/173848\/revisions\/173853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/23864"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=173848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=173848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=173848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}