{"id":172975,"date":"2025-02-12T12:37:27","date_gmt":"2025-02-12T18:37:27","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=172975"},"modified":"2025-02-12T12:37:30","modified_gmt":"2025-02-12T18:37:30","slug":"sheinbaum-critica-propuesta-del-pan-para-fijar-tope-en-precio-de-la-gasolina","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/02\/12\/sheinbaum-critica-propuesta-del-pan-para-fijar-tope-en-precio-de-la-gasolina\/","title":{"rendered":"Sheinbaum critica propuesta del PAN para fijar tope en precio de la gasolina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta\u00a0<strong>Claudia Sheinbaum Pardo<\/strong>\u00a0critic\u00f3 que legisladores del Partido Acci\u00f3n Nacional\u00a0<strong>(PAN)<\/strong>\u00a0presentaron oficialmente una iniciativa para fijar un precio m\u00e1ximo de 20 pesos al<strong>\u00a0litro de gasolina<\/strong>\u00a0en todo el pa\u00eds, al considerarlo una\u00a0<strong>hipocres\u00eda<\/strong>, pues acus\u00f3 que en administraciones anteriores se promovi\u00f3 el aumento en el costo de los combustibles.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cHay mucha hipocres\u00eda, enga\u00f1o, nada m\u00e1s que el pueblo est\u00e1 muy informado ahora. Es totalmente demag\u00f3gico e hip\u00f3crita decir que ahora quieren bajar los precios de la gasolina cuando ellos fueron los de los gasolinazos.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/02\/12\/sheinbaum-reacciona-a-la-nominacion-de-terry-cole-como-el-nuevo-director-de-la-dea-colaboracion-pero-sin-injerencias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cRecuerden, en la \u00e9poca de Felipe Calder\u00f3n y de Pe\u00f1a Nieto fue cuando m\u00e1s aument\u00f3 el precio de la gasolina. \u00bfQu\u00e9 estamos haciendo ahora? Lo que no queremos es que haya abusos de los gasolineros, m\u00e1s que fijar un precio o una ganancia m\u00e1xima, lo que queremos es llegar a un acuerdo con ellos, ya va muy avanzado el acuerdo, y el objetivo es que el precio de la gasolina no suba de 24 pesos el litro, que considerando la inflaci\u00f3n, pues no solo con ese precio no habr\u00eda aumento desde 2018, sino que inclusive habr\u00eda una ligera reducci\u00f3n del precio del 2018\u2033, dijo en su conferencia ma\u00f1anera.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2025\/02\/12\/sheinbaum-critica-propuesta-del-pan-para-fijar-precio-de-la-gasolina-hay-mucha-hipocresia\/?utm_cmp_rs=ifc%3AFC_pkPMe9MoSnmEyVpsHRvb5A\">Infobae<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta\u00a0Claudia Sheinbaum Pardo\u00a0critic\u00f3 que legisladores del Partido Acci\u00f3n Nacional\u00a0(PAN)\u00a0presentaron oficialmente una iniciativa para fijar un precio m\u00e1ximo de 20 pesos al\u00a0litro de gasolina\u00a0en todo el pa\u00eds, al considerarlo una\u00a0hipocres\u00eda, pues acus\u00f3 que en administraciones anteriores se promovi\u00f3 el aumento en el costo de los combustibles. \u201cHay mucha hipocres\u00eda, enga\u00f1o, nada m\u00e1s que el pueblo [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":117570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,2807,284],"class_list":["post-172975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-gasolina","tag-pan","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/172975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=172975"}],"version-history":[{"count":5,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/172975\/revisions"}],"predecessor-version":[{"id":172980,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/172975\/revisions\/172980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/117570"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=172975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=172975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=172975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}