{"id":171704,"date":"2025-02-03T09:52:41","date_gmt":"2025-02-03T15:52:41","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=171704"},"modified":"2025-02-03T09:52:43","modified_gmt":"2025-02-03T15:52:43","slug":"anuncia-claudia-sheinbaum-pausa-de-aranceles-tras-llamada-con-donald-trump","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/02\/03\/anuncia-claudia-sheinbaum-pausa-de-aranceles-tras-llamada-con-donald-trump\/","title":{"rendered":"Anuncia Claudia Sheinbaum pausa de aranceles tras llamada con Donald Trump"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta de M\u00e9xico Claudia Sheinbaum Pardo anunci\u00f3 que Estados Unidos pondr\u00e1 en \u201cpausa\u201d por un mes los aranceles de 25 por ciento a productos mexicanos anunciados por su hom\u00f3logo Donald Trump. Lo anterior como resultado de una llamada telef\u00f3nica que sostuvieron la ma\u00f1ana de este lunes.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/02\/03\/la-mananera-de-claudia-sheinbaum-hoy-3-de-febrero-en-vivo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un breve mensaje publicado en sus redes sociales, la mandataria federal dijo que se comprometi\u00f3 a reforzar la frontera con Estados Unidos con 10 mil elementos de la Guardia Nacional, quienes se encargar\u00e1n de evitar el tr\u00e1fico de drogas, en particular fentanilo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la conferencia de prensa de este lunes, asegur\u00f3 que orden\u00f3 al secretario de la Defensa Nacional (Sedena), Ricardo Trevilla Trejo, para que atienda la solicitud de reforzar la seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que por el lado del gobierno estadounidense, se comprometi\u00f3 a trabajar para evitar el tr\u00e1fico de armas de alto poder a M\u00e9xico, mismas que son utilizadas por las organizaciones del crimen organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2025\/02\/03\/claudia-sheinbaum-anuncia-pausa-de-aranceles-tras-llamada-con-donald-trump\/\">Infobae<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de M\u00e9xico Claudia Sheinbaum Pardo anunci\u00f3 que Estados Unidos pondr\u00e1 en \u201cpausa\u201d por un mes los aranceles de 25 por ciento a productos mexicanos anunciados por su hom\u00f3logo Donald Trump. Lo anterior como resultado de una llamada telef\u00f3nica que sostuvieron la ma\u00f1ana de este lunes. A trav\u00e9s de un breve mensaje publicado en [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":166598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[14569,2801,230,162],"class_list":["post-171704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-aranceles","tag-claudia-sheinbaum","tag-donald-trump","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/171704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=171704"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/171704\/revisions"}],"predecessor-version":[{"id":171708,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/171704\/revisions\/171708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/166598"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=171704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=171704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=171704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}