{"id":170988,"date":"2025-01-27T12:47:47","date_gmt":"2025-01-27T18:47:47","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=170988"},"modified":"2025-01-27T12:47:48","modified_gmt":"2025-01-27T18:47:48","slug":"reacciona-sheinbaum-a-determinacion-del-tepjf-para-que-el-senado-sustituya-al-comite-del-poder-judicial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/01\/27\/reacciona-sheinbaum-a-determinacion-del-tepjf-para-que-el-senado-sustituya-al-comite-del-poder-judicial\/","title":{"rendered":"Reacciona Sheinbaum a determinaci\u00f3n del TEPJF para que el Senado sustituya al Comit\u00e9 del Poder Judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cEn proceso electorales,\u00a0<strong>la \u00faltima palabra la tiene la Sala Superior del Tribunal Electoral<\/strong>\u201d, dijo la presidenta\u00a0<strong>Claudia Sheinbaum Pardo<\/strong>\u00a0al ser cuestionada sobre su posici\u00f3n respecto al proyecto que present\u00f3 hoy la magistrada presidenta M\u00f3nica Soto para que sea el<strong>\u00a0Senado el que sustituya al Comit\u00e9 de Evaluaci\u00f3n del Poder Judicial (CEPJ) y realice los \u00faltimos procedimientos de selecci\u00f3n\u00a0<\/strong>de los aspirantes a jueces, magistrados y ministros.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/27\/tepjf-da-luz-verde-al-senado-para-sustituir-al-comite-del-poder-judicial-en-la-evaluacion-de-aspirantes-a-jueces\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 que<strong>\u00a0con esta determinaci\u00f3n se salvaguardaban los derechos de los aspirantes<\/strong>que respondieron \u00fanicamente a la convocatoria del CEPJ, que en caso de no solucionarse el conflicto a tiempo se quedar\u00edan sin la oportunidad de participar.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cMe parece muy bien que el Tribunal Electoral diga c\u00f3mo salvaguardamos los derechos de estas personas que est\u00e1n participando, que decidieron inscribirse y participar en el Poder Judicial. La Constituci\u00f3n dice que es hasta el 31 de enero para tener los nombres de las personas que van a participar en la elecci\u00f3n. Entonces me parece muy bien que el Tribunal Electoral diga: \u2018si la Corte no quiere (entonces) que se vaya al Legislativo o Ejecutivo\u2018\u00a0<strong>es un mecanismo que permita que se salvaguarden los derechos de las personas<\/strong>\u00a0que se inscribieron en el Poder Judicial\u00a0<strong>y que despu\u00e9s no tengan un pretexto de decir que la elecci\u00f3n no fue correcta o tuvo un problema<\/strong>\u201d, coment\u00f3 en la conferencia de prensa de este lunes.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/27\/sheinbaum-reacciona-a-determinacion-del-tepjf-para-que-el-senado-sustituya-al-comite-del-poder-judicial\/\">Infobae<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEn proceso electorales,\u00a0la \u00faltima palabra la tiene la Sala Superior del Tribunal Electoral\u201d, dijo la presidenta\u00a0Claudia Sheinbaum Pardo\u00a0al ser cuestionada sobre su posici\u00f3n respecto al proyecto que present\u00f3 hoy la magistrada presidenta M\u00f3nica Soto para que sea el\u00a0Senado el que sustituya al Comit\u00e9 de Evaluaci\u00f3n del Poder Judicial (CEPJ) y realice los \u00faltimos procedimientos de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":58369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,162,1791],"class_list":["post-170988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-portada","tag-tepjf","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=170988"}],"version-history":[{"count":5,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170988\/revisions"}],"predecessor-version":[{"id":170995,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170988\/revisions\/170995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/58369"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=170988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=170988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=170988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}