{"id":170451,"date":"2025-01-22T09:44:02","date_gmt":"2025-01-22T15:44:02","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=170451"},"modified":"2025-01-22T09:44:04","modified_gmt":"2025-01-22T15:44:04","slug":"sheinbaum-anuncia-inicio-de-conversaciones-formales-con-el-gobierno-de-trump","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/01\/22\/sheinbaum-anuncia-inicio-de-conversaciones-formales-con-el-gobierno-de-trump\/","title":{"rendered":"Sheinbaum anuncia inicio de conversaciones formales con el gobierno de Trump"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta<strong>\u00a0Claudia Sheinbaum Pardo\u00a0<\/strong>comparti\u00f3 que ayer inici\u00f3 el di\u00e1logo formal entre el gobierno de los Estados Unidos, revel\u00f3 que\u00a0<strong>Juan Ram\u00f3n de la Fuente<\/strong>, canciller de M\u00e9xico,\u00a0<strong>sostuvo una llamada telef\u00f3nica con Marco Rubio<\/strong>, secretario de Estado, despu\u00e9s de que jur\u00f3 para asumir el cargo.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/21\/eduardo-ruiz-healy-critica-a-lilly-tellez-tras-lamentar-que-eeuu-no-invito-a-sheinbaum-a-investidura-de-trump\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria coment\u00f3 que la conversaci\u00f3n que sostuvieron los funcionarios de ambas naciones<strong>&nbsp;fue \u201cbuena y muy cordial\u201d<\/strong>&nbsp;en la que discutieron temas de&nbsp;<strong>migraci\u00f3n y seguridad<\/strong>, ello despu\u00e9s de que el presidente Donald Trump firm\u00f3 decretos para endurecer sus pol\u00edticas migratorias y en contra de los C\u00e1rteles.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201c<strong>Iniciaron ya las conversaciones (M\u00e9xico &#8211; Estados Unidos), fue una muy buena conversaci\u00f3n, muy cordial<\/strong>. Se habl\u00f3 de temas de migraci\u00f3n, de seguridad y a partir del d\u00eda de ayer inician ya estas conversaciones (&#8230;)&nbsp;<strong>Fue la primera llamad del secretario de Estado<\/strong>, Marco Rubio, la primera que hizo fue a M\u00e9xico y fue una llamada muy cordial, me inform\u00f3 el canciller\u201d, dijo en la conferencia de prensa de este mi\u00e9rcoles.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria federal dijo que hasta el momento\u00a0<strong>no se tiene previsto que se lleve a cabo una reuni\u00f3n de alto nivel<\/strong>, sin embargo,\u00a0<strong>considera que se llegar\u00e1n a acuerdos en los diferentes temas<\/strong>, pues -como ha dicho anteriormente- espera que se pueda trabajar en coordinaci\u00f3n y con respeto a la independencia de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/22\/sheinbaum-anuncia-inicio-de-conversaciones-formales-con-el-gobierno-de-trump-fue-muy-cordial\/\">Infobae<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta\u00a0Claudia Sheinbaum Pardo\u00a0comparti\u00f3 que ayer inici\u00f3 el di\u00e1logo formal entre el gobierno de los Estados Unidos, revel\u00f3 que\u00a0Juan Ram\u00f3n de la Fuente, canciller de M\u00e9xico,\u00a0sostuvo una llamada telef\u00f3nica con Marco Rubio, secretario de Estado, despu\u00e9s de que jur\u00f3 para asumir el cargo. La mandataria coment\u00f3 que la conversaci\u00f3n que sostuvieron los funcionarios de ambas [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":55532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,230,162],"class_list":["post-170451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-donald-trump","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=170451"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170451\/revisions"}],"predecessor-version":[{"id":170455,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/170451\/revisions\/170455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/55532"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=170451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=170451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=170451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}