{"id":169772,"date":"2025-01-15T11:01:47","date_gmt":"2025-01-15T17:01:47","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=169772"},"modified":"2025-01-15T11:01:49","modified_gmt":"2025-01-15T17:01:49","slug":"sheinbaum-reacciona-a-denuncia-contra-ministras-por-actos-anticipados-de-campana","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/01\/15\/sheinbaum-reacciona-a-denuncia-contra-ministras-por-actos-anticipados-de-campana\/","title":{"rendered":"Sheinbaum reacciona a denuncia contra ministras por actos anticipados de campa\u00f1a"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n civil Defensorxs present\u00f3 una\u00a0<strong>denuncia\u00a0<\/strong>en contra de las\u00a0<strong>ministras Lenia Batres<\/strong>\u00a0Guadarrama,\u00a0<strong>Yasm\u00edn Esquivel<\/strong>\u00a0Mossa y<strong>\u00a0Loretta Ortiz<\/strong>\u00a0Ahlf por incurrir en presuntos\u00a0<strong>actos anticipados de campa\u00f1a<\/strong>, ya que estar\u00edan llamado en eventos y redes sociales a votar por ellas en las\u00a0<strong>elecciones del Poder Judicial\u00a0<\/strong>que se celebrar\u00e1n el pr\u00f3ximo\u00a0<strong>1 de junio<\/strong>.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/14\/sheinbaum-reacciona-a-mantas-contra-mandos-militares-colocadas-en-elota-sinaloa-no-necesariamente-dicen-la-verdad\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuestionada sobre esta queja interpuesta ante el Instituto Nacional Electoral (INE), la&nbsp;<strong>presidenta Claudia Sheinbaum<\/strong>&nbsp;Pardo solt\u00f3 una carcajada y luego dijo que ya era tiempo de que se den a conocer las reglas para estos comicios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Es muy pertinente que el INE saque ya las reglas<\/strong>, porque cuando estuvieron aqu\u00ed yo les preguntaba si era factible que un\u00a0<strong>partido\u00a0<\/strong>pol\u00edtico o el\u00a0<strong>gobierno promoviera el voto<\/strong>, no a un candidato pero s\u00ed a salir a votar el 1 de junio, para hacer muy participativa la elecci\u00f3n, c\u00f3mo votar, en fin, ellos plantearon que cada uno ten\u00eda consideraciones distintas, es importante que el INE -lo m\u00e1s pronto posible- diga cu\u00e1les son las reglas\u201d, sentenci\u00f3 en La Ma\u00f1anera del Pueblo de este 15 de enero.<a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/15\/la-mananera-de-claudia-sheinbaum-hoy-15-de-enero-en-vivo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheinbaum Pardo dijo, por ejemplo, que ella considera que los partidos pol\u00edticos s\u00ed podr\u00edan hacer llamados a participar en la elecci\u00f3n judicial mas no por votar en favor de un candidato en espec\u00edfico o a escudarse en asociaciones civiles en detrimento de alg\u00fan aspirante, y reiter\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQue se emitan las&nbsp;<strong>reglas claras<\/strong>&nbsp;ahora que terminen los comit\u00e9s (de evaluaci\u00f3n) de elegir, el 31 de enero ya van a tener qui\u00e9n va a participar y de ah\u00ed pueda el INE con tiempo y anticipaci\u00f3n difundir qui\u00e9nes son los candidatos y para qu\u00e9 puesto van, todo lo que vamos a votar\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2025\/01\/15\/sheinbaum-reacciona-a-denuncia-contra-ministras-por-actos-anticipados-de-campana-el-ine-debe-sacar-ya-reglas-claras\/\">Infobae<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n civil Defensorxs present\u00f3 una\u00a0denuncia\u00a0en contra de las\u00a0ministras Lenia Batres\u00a0Guadarrama,\u00a0Yasm\u00edn Esquivel\u00a0Mossa y\u00a0Loretta Ortiz\u00a0Ahlf por incurrir en presuntos\u00a0actos anticipados de campa\u00f1a, ya que estar\u00edan llamado en eventos y redes sociales a votar por ellas en las\u00a0elecciones del Poder Judicial\u00a0que se celebrar\u00e1n el pr\u00f3ximo\u00a01 de junio. Cuestionada sobre esta queja interpuesta ante el Instituto Nacional Electoral [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":166502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,162],"class_list":["post-169772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/169772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=169772"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/169772\/revisions"}],"predecessor-version":[{"id":169775,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/169772\/revisions\/169775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/166502"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=169772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=169772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=169772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}