{"id":167604,"date":"2024-12-19T11:25:15","date_gmt":"2024-12-19T17:25:15","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=167604"},"modified":"2024-12-19T11:25:17","modified_gmt":"2024-12-19T17:25:17","slug":"claudia-sheinbaum-preve-la-creacion-del-auto-mexicano","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/19\/claudia-sheinbaum-preve-la-creacion-del-auto-mexicano\/","title":{"rendered":"Claudia Sheinbaum prev\u00e9 la creaci\u00f3n del \u2018Auto Mexicano\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Como parte de su plan de trabajo en la presidencia de M\u00e9xico,\u00a0<strong>Claudia Sheinbaum Pardo<\/strong>, ha refrendado en m\u00faltiples ocasiones su compromiso por el desarrollo tecnol\u00f3gico en el pa\u00eds. Rumbo al 2025, la mandataria anunci\u00f3 el incremento de proyectos enfocados a incentivar la innovaci\u00f3n y potencial cient\u00edfico por el beneficio del pa\u00eds, ejemplo de ello es la creaci\u00f3n del primer\u00a0<strong>Autom\u00f3vil Mexicano.<\/strong><a href=\"https:\/\/www.infobae.com\/mexico\/2024\/12\/19\/sheinbaum-reacciona-al-asesinato-de-agente-de-la-sspc-en-culiacan-fue-en-cumplimiento-de-su-deber\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su intervenci\u00f3n con medios, la titular del Ejecutivo adelant\u00f3 la ejecuci\u00f3n del algunos proyectos en materia tecnol\u00f3gica, entre ellos el primer\u00a0<strong>veh\u00edculo de \u00edndole nacional,<\/strong>\u00a0el cual se busca que sea desarrollado al interior de pa\u00eds en atenci\u00f3n de los mexicanos. En cuanto a los detalles del proyecto, la dirigencia los presentar\u00e1 poco a poco en el pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2024\/12\/19\/claudia-sheinbaum-preve-la-creacion-del-auto-mexicano-aqui-los-detalles-del-proyecto\/\">Infobae<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de su plan de trabajo en la presidencia de M\u00e9xico,\u00a0Claudia Sheinbaum Pardo, ha refrendado en m\u00faltiples ocasiones su compromiso por el desarrollo tecnol\u00f3gico en el pa\u00eds. Rumbo al 2025, la mandataria anunci\u00f3 el incremento de proyectos enfocados a incentivar la innovaci\u00f3n y potencial cient\u00edfico por el beneficio del pa\u00eds, ejemplo de ello es [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":166444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[31387,2801],"class_list":["post-167604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-auto-mexicano","tag-claudia-sheinbaum","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=167604"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167604\/revisions"}],"predecessor-version":[{"id":167605,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167604\/revisions\/167605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/166444"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=167604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=167604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=167604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}