{"id":167549,"date":"2024-12-18T11:05:56","date_gmt":"2024-12-18T17:05:56","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=167549"},"modified":"2024-12-18T11:05:59","modified_gmt":"2024-12-18T17:05:59","slug":"constructoras-veracruzanas-son-respetuosas-de-la-entrega-de-aguinaldos-y-aumento-al-salario","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/18\/constructoras-veracruzanas-son-respetuosas-de-la-entrega-de-aguinaldos-y-aumento-al-salario\/","title":{"rendered":"Constructoras veracruzanas son respetuosas de la entrega de aguinaldos y aumento al salario"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las constructoras veracruzanas se encuentran conscientes de que los trabajadores necesitan mejorar su poder adquisitivo y se cumplir\u00e1 con lo estipulado en la ley de incrementar el 12 por ciento al salario m\u00ednimo, sin embargo,Jorge Alard\u00edn C\u00f3rdova, presidente de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n (CMIC) delegaci\u00f3n Veracruz, admiti\u00f3  que s\u00ed podr\u00eda afectar un aumento para el pr\u00f3ximo a\u00f1o de 15 a 30 d\u00edas de aguinaldo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nosotros estamos obligados, y como lo marque la ley para nuestros trabajadores, la realidad evidentemente nos pega a todos, no hay solvencia econ\u00f3mica, no hay muchas oportunidades, mucha solvencia econ\u00f3mica, pero definitivamente tenemos que encontrar la manera para poder seguir adelante&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo se\u00f1al\u00f3 que las constructoras veracruzanas est\u00e1n cumpliendo con la entrega de aguinaldos a los trabajadores, pero insisti\u00f3 que impactar\u00e1 a las empresas un aumento de los d\u00edas de la prestaci\u00f3n, pues se tendr\u00eda que pagar el doble a cada trabajador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El art\u00edculo 87 de la Ley Federal del Trabajo (LFT), garantiza a los trabajadores al menos 15 d\u00edas de salario como pago anual antes del 20 de diciembre, la iniciativa de reforma que podr\u00eda aprobarse es de que la cantidad de d\u00edas se duplique a 30.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente confi\u00f3 que en 2025 las constructoras veracruzanas participen en la realizaci\u00f3n de infraestructura y obra p\u00fablica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Los veracruzanos estamos contentos con el nuevo cambio de estafeta que se dio, con el nuevo gobierno, nos sentimos muy incluidos y escuchados, y que las cosas van a cambiar favorablemente&#8221;, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias Las constructoras veracruzanas se encuentran conscientes de que los trabajadores necesitan mejorar su poder adquisitivo y se cumplir\u00e1 con lo estipulado en la ley de incrementar el 12 por ciento al salario m\u00ednimo, sin embargo,Jorge Alard\u00edn C\u00f3rdova, presidente de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n (CMIC) delegaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":85721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[7585,3109,1558,1941],"class_list":["post-167549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-aguinaldo","tag-aumento","tag-constructoras","tag-salario","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=167549"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167549\/revisions"}],"predecessor-version":[{"id":167550,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167549\/revisions\/167550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/85721"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=167549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=167549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=167549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}