{"id":167198,"date":"2024-12-12T13:11:51","date_gmt":"2024-12-12T19:11:51","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=167198"},"modified":"2024-12-12T13:11:52","modified_gmt":"2024-12-12T19:11:52","slug":"regresa-perro-salado-un-homenaje-a-la-era-dorada-de-la-musica-disco-en-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/12\/regresa-perro-salado-un-homenaje-a-la-era-dorada-de-la-musica-disco-en-veracruz\/","title":{"rendered":"Regresa Perro Salado, un homenaje a la era dorada de la m\u00fasica disco en Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo 27 de diciembre, el Sal\u00f3n Baalbeck en Boca del R\u00edo ser\u00e1 testigo de un evento \u00fanico que busca revivir la magia de discoteca Perro Salado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este lugar, \u00edcono del entretenimiento en Veracruz durante los a\u00f1os 70 y 80, marc\u00f3 a varias generaciones con su ambiente innovador y su m\u00fasica inolvidable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento, organizado por Jorge Malpica, hijo del fundador de la discoteca, Jorge Malpica Mart\u00ednez, dijo que el evento promete transportar a los asistentes a aquella \u00e9poca dorada con m\u00fasica disco en vinilo, recuerdos y una atm\u00f3sfera de nostalgia compartida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSon 22 a\u00f1os, es el evento oficial de Perro Salado, la Disco de los Jefes y el concepto es Por Fin es Viernes. Ser\u00e1 a partir de las 9 de la noche. Es el \u00fanico evento oficial de Perro Salado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inaugurado el 11 de enero de 1977 por Jorge Malpica Mart\u00ednez, Perro Salado se convirti\u00f3 r\u00e1pidamente en un referente del entretenimiento local y nacional. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rafael Aguirre Boss, quien fue DJ dePerro Salado, dijo que no era solo una discoteca, era un centro cultural y social que marc\u00f3 un antes y un despu\u00e9s en Veracruz. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello la intenci\u00f3n es reunir a tres generaciones en una noche de celebraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue la primera discoteca que nace en Veracruz con el equipo necesario que se trajo de Estados Unidos. Era una \u00e9poca conservadora, antes ir no era f\u00e1cil\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El homenaje del 27 de diciembre no ser\u00e1 simplemente una fiesta, sino una experiencia completa para revivir la esencia de Perro Salado.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos est\u00e1n disponibles bajo el nombre Perro Salado, la disco de los jefes, con precios de $450 VIP 1, $350 VIP 2 y $250 VIP 3. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pueden adquirirse a trav\u00e9s de redes sociales o contactando directamente a los n\u00fameros: 2299 011111, 2291845383 y 2294128636.En la rueda de prensa tambi\u00e9n estuvieron presentes el DJ Marco Maldonado y el DJ Armando Vel\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias El pr\u00f3ximo 27 de diciembre, el Sal\u00f3n Baalbeck en Boca del R\u00edo ser\u00e1 testigo de un evento \u00fanico que busca revivir la magia de discoteca Perro Salado. Este lugar, \u00edcono del entretenimiento en Veracruz durante los a\u00f1os 70 y 80, marc\u00f3 a varias generaciones con su ambiente innovador y su [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":167199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[29443],"class_list":["post-167198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-perro-salado","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=167198"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167198\/revisions"}],"predecessor-version":[{"id":167200,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/167198\/revisions\/167200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/167199"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=167198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=167198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=167198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}