{"id":166995,"date":"2024-12-10T12:14:36","date_gmt":"2024-12-10T18:14:36","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=166995"},"modified":"2024-12-10T12:14:38","modified_gmt":"2024-12-10T18:14:38","slug":"sheinbaum-reacciona-a-boda-en-el-munal","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/10\/sheinbaum-reacciona-a-boda-en-el-munal\/","title":{"rendered":"Sheinbaum reacciona a boda en el MUNAL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta\u00a0<strong>Claudia Sheinbaum Pardo<\/strong> se\u00f1al\u00f3 que debe aclararse el caso de\u00a0<strong>Mart\u00edn Borrego<\/strong>, funcionario de la Secretar\u00eda de Medio Ambiente, por el presunto uso de las\u00a0<strong>instalaciones del MUNAL<\/strong>\u00a0para la<strong>\u00a0celebraci\u00f3n de su boda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo deben usarse espacios p\u00fablicos para ninguna conmemoraci\u00f3n, celebraci\u00f3n o actividad. Evidentemente hay actividades de Relaciones Exteriores y de otras secretar\u00edas que tienen que ver con reuniones protocolarias que se realizan, pero no fiestas\u201d, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodos los servidores p\u00fablicos deben comportarse adecuadamente, ya informar\u00e1 la secretaria de Medio Ambiente sobre este caso\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 la carta que envi\u00f3 a los servidores p\u00fablicos al inicio de su gobierno, donde les pide predicar con el ejemplo de un gobierno honesto y austero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSu comportamiento y desempe\u00f1o debe ser evitar condenar las malas pr\u00e1cticas propias del r\u00e9gimen que hemos superado, sin influyentismo, nepotismo, sin corrupci\u00f3n ni impunidad\u201d, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/sheinbaum-reacciona-a-boda-en-el-munal-tiene-que-investigarse-pide-no-usar-espacios-publicos-para-fiestas\/\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta\u00a0Claudia Sheinbaum Pardo se\u00f1al\u00f3 que debe aclararse el caso de\u00a0Mart\u00edn Borrego, funcionario de la Secretar\u00eda de Medio Ambiente, por el presunto uso de las\u00a0instalaciones del MUNAL\u00a0para la\u00a0celebraci\u00f3n de su boda. \u201cNo deben usarse espacios p\u00fablicos para ninguna conmemoraci\u00f3n, celebraci\u00f3n o actividad. Evidentemente hay actividades de Relaciones Exteriores y de otras secretar\u00edas que tienen que [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":166997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[2801,31335],"class_list":["post-166995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-claudia-sheinbaum","tag-munal","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=166995"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166995\/revisions"}],"predecessor-version":[{"id":166999,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166995\/revisions\/166999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/166997"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=166995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=166995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=166995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}