{"id":166894,"date":"2024-12-09T11:14:56","date_gmt":"2024-12-09T17:14:56","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=166894"},"modified":"2024-12-09T11:14:58","modified_gmt":"2024-12-09T17:14:58","slug":"capellania-armada-mundial-de-paz-realiza-actividades-sociales-en-la-zona-de-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/09\/capellania-armada-mundial-de-paz-realiza-actividades-sociales-en-la-zona-de-veracruz\/","title":{"rendered":"Capellan\u00eda Armada Mundial de Paz realiza actividades sociales en la zona de Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Cuerpo Diplom\u00e1tico Capellan\u00eda Armada Mundial de Paz, \u00f1 llev\u00f3 a cabo una serie de actividades de impacto social en los municipios conurbados reafirmando su compromiso con el bienestar comunitario y la promoci\u00f3n de valores.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las acciones destacadas, se realiz\u00f3 una jornada de limpieza en la playa Villa del Mar en Veracruz, con el objetivo de fomentar el cuidado del medio ambiente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se hizo una donaci\u00f3n de tapitas en apoyo a Iyari, una ni\u00f1a que enfrenta la lucha contra la fibrosis qu\u00edstica, sum\u00e1ndose a la causa con este gesto solidario.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00e1mbito educativo, se impartieron pl\u00e1ticas de prevenci\u00f3n del delito y derechos humanos en diversas instituciones de la regi\u00f3n, entre ellas el Ilustre Instituto Veracruzano y el TEBA Medell\u00edn 20 de Noviembre en Boca del R\u00edo y Medell\u00edn. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se visitaron las escuelas Telesecundaria Adolfo L\u00f3pez Mateos en la cabecera municipal de Medell\u00edn, Telesecundaria Justo Sierra y el Bachillerato Ignacio Manuel Altamirano, ambos en El Tejar, donde se promovi\u00f3 la participaci\u00f3n ciudadana y el compromiso con acciones en beneficio de la comunidad.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El grupo tambi\u00e9n mostr\u00f3 su apoyo a sectores vulnerables mediante una visita al asilo COGRA, donde convivieron con los abuelitos y ayudaron a servir los alimentos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, la artista Yatsuri Visoso ofreci\u00f3 una emotiva presentaci\u00f3n musical para alegrar a los presentes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se realiz\u00f3 una visita al asilo Do\u00f1a Nico en Boca del R\u00edo, llevando momentos de compa\u00f1\u00eda y afecto.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actividades contaron con la participaci\u00f3n activa de la Mtra. Martha Villegas, presidenta del Cuerpo Diplom\u00e1tico Mundial de Paz Boinas Azules.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Capell\u00e1n Pablo L\u00f3pez Favila agradeci\u00f3 la colaboraci\u00f3n de todos los participantes y destac\u00f3 que estas acciones refuerzan los lazos de solidaridad y fortalecen el tejido social en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias El Cuerpo Diplom\u00e1tico Capellan\u00eda Armada Mundial de Paz, \u00f1 llev\u00f3 a cabo una serie de actividades de impacto social en los municipios conurbados reafirmando su compromiso con el bienestar comunitario y la promoci\u00f3n de valores. Entre las acciones destacadas, se realiz\u00f3 una jornada de limpieza en la playa Villa del [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":166895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[31320,31319],"class_list":["post-166894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-actividades-sociales","tag-capellania-armada-mundial-de-paz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=166894"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166894\/revisions"}],"predecessor-version":[{"id":166896,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166894\/revisions\/166896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/166895"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=166894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=166894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=166894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}