{"id":166790,"date":"2024-12-08T18:16:53","date_gmt":"2024-12-09T00:16:53","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=166790"},"modified":"2024-12-08T18:16:54","modified_gmt":"2024-12-09T00:16:54","slug":"el-15-de-diciembre-verificaran-la-legibilidad-de-los-inscritos-a-la-eleccion-del-poder-judicial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/08\/el-15-de-diciembre-verificaran-la-legibilidad-de-los-inscritos-a-la-eleccion-del-poder-judicial\/","title":{"rendered":"El 15 de diciembre verificar\u00e1n la legibilidad de los inscritos a la elecci\u00f3n del Poder Judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Urrilla | NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz, Ver. M\u00e1s de 34 mil personas de inscribieron para contender en las elecciones de julio de 2025, para ser jueces, magistrados y ministros. Se inscribieron ante el Comit\u00e9 de Evaluaci\u00f3n 18 mil 447 personas por parte del Poder Ejecutivo, as\u00ed como 11 mil 904 desde el Poder Legislativo y hubo mil 805 solicitudes de aspirantes en el sitio del Comit\u00e9 de Evaluaci\u00f3n del Poder Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luis Gabriel Aguilar Virgen, secretario de Tribunal Colegiado adscrito al Primer Tribunal Colegiado en Materia Penal &nbsp;del S\u00e9ptimo Circuito, llam\u00f3 a cuidar los perfiles de los finalistas ya que de lo contrario se pondr\u00eda en riesgo la impartici\u00f3n de justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo he platicado con compa\u00f1eros y creemos que debemos ser nosotros mismos, que vemos que se nos va a truncar la carrera judicial, quienes nos podamos postular para estar en la boleta. Hay que cumplir los requisitos. Nosotros seguimos prepar\u00e1ndonos para participar y reiterar que nosotros mismos debemos darle confianza a la gente de que la impartici\u00f3n de justicia va a seguir siendo de calidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los comit\u00e9s de evaluaci\u00f3n se encuentran conformados por personas que revisar\u00e1n los perfiles que se inscribieron y de ellos depender\u00e1 elegir a los mejores. Aguilar Virgen record\u00f3 que muchos trabajadores del Poder Judicial se prepararon durante a\u00f1os para ser titulares de un \u00f3rgano jurisdiccional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos que estamos en la trinchera, en el primer contacto con la gente, hemos estado por a\u00f1os capacit\u00e1ndonos y tratando de llegar a ser titulares de un \u00f3rgano jurisdiccional y con esta nueva manera de elegir a estos titulares no se va a poder tan f\u00e1cilmente o al menos no lo sabemos. Ya va a depender de otros factores, no de la capacitaci\u00f3n y preparaci\u00f3n, ese es el riesgo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la elecci\u00f3n mediante el voto, de magistrados, jueces y ministros, dijo que el m\u00e9todo no es nuevo ya que a lo largo de la historia se eleg\u00eda de una forma similar. Agreg\u00f3 que la impartici\u00f3n de justicia puede ponerse en riesgo si los comit\u00e9s de evaluaci\u00f3n no eligen a los mejores perfiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo por votaci\u00f3n popular directa pero s\u00ed de manera indirecta a los ministros. Ahorita lo que se trata es de una electorizaci\u00f3n de la manera en que magistrados, jueces y ministros van a llegar a los puestos. Es discutible desde luego, dependiendo de que partido le llaman de una forma u otra\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es de mencionar que la convocatoria cerr\u00f3 el 24 de noviembre. El 15 de diciembre los comit\u00e9s verificar\u00e1n la legibilidad. Posteriormente el 31 de enero de 2025ser\u00e1n las entrevistas y selecci\u00f3n de finalistas. El 4 de febrero de 2025, los poderes determinar\u00e1n la conformidad de finalistas. El 5 de febrero de 2025 los comit\u00e9s seleccionar\u00e1n los listados. El 7 de febreroser\u00e1 la aprobaci\u00f3n de listados. El 12 de febrero el Senado integrar\u00e1, revisar\u00e1 y remitir\u00e1 el listado al INE y el 1 de junio de 2025 ser\u00e1 la elecci\u00f3n de jueces, magistrados y ministros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Urrilla | NV Noticias Veracruz, Ver. M\u00e1s de 34 mil personas de inscribieron para contender en las elecciones de julio de 2025, para ser jueces, magistrados y ministros. Se inscribieron ante el Comit\u00e9 de Evaluaci\u00f3n 18 mil 447 personas por parte del Poder Ejecutivo, as\u00ed como 11 mil 904 desde el Poder Legislativo y [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":163734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[2321],"class_list":["post-166790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-poder-judicial","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=166790"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166790\/revisions"}],"predecessor-version":[{"id":166791,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166790\/revisions\/166791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/163734"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=166790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=166790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=166790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}