{"id":166219,"date":"2024-12-01T12:35:00","date_gmt":"2024-12-01T18:35:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=166219"},"modified":"2024-12-01T22:37:34","modified_gmt":"2024-12-02T04:37:34","slug":"bloquean-jb-lobos-para-exigir-la-aparicion-con-vida-de-betzi-lopez","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/12\/01\/bloquean-jb-lobos-para-exigir-la-aparicion-con-vida-de-betzi-lopez\/","title":{"rendered":"Bloquean JB Lobos para exigir la aparici\u00f3n con vida de\u00a0 Betzi L\u00f3pez\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>Jes\u00fas Utrilla | NV Noticias <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Familiares y conocidos de la joven Betzi L\u00f3pez Estudillo, de 19 a\u00f1os de edad, bloquearon la avenida JB Lobos en el Puerto de Veracruz para exigir su pronta aparici\u00f3n con vida. La joven desapareci\u00f3 el 30 de noviembre despu\u00e9s de ir al centro de Veracruz a realizar unas compras en compa\u00f1\u00eda de una conocida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Seg\u00fan Zurizaday L\u00f3pez, hermana de Betzi, la joven sali\u00f3 con una se\u00f1ora llamada Olga Guillermo Delgado, quien es compa\u00f1era de trabajo de Betzi en una cocina econ\u00f3mica en la colonia Sotavento. Sin embargo, despu\u00e9s de las 6:30 de la tarde, Betzi dej\u00f3 de contestar su tel\u00e9fono y no regres\u00f3 a su casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La familia de Betzi acusa a la se\u00f1ora de no haber avisado sobre la desaparici\u00f3n de la joven y de no contestar las llamadas ni los mensajes. Por lo tanto, familiares y conocidos temen que Betzi haya sido secuestrada en complicidad de su compa\u00f1era de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La avenida JB Lobos fue bloqueada en ambos sentidos, provocando caos vial y la molestia de algunos automovilistas. La familia de Betzi exige a la fiscal\u00eda que agilice la b\u00fasqueda y se investigue a los sospechosos. La desaparici\u00f3n de Betzi L\u00f3pez Estudillo ha generado una gran preocupaci\u00f3n\u00a0 y se espera que las autoridades tomen medidas urgentes para encontrar a la joven.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Familiares y conocidos de la joven Betzi L\u00f3pez Estudillo, de 19 a\u00f1os de edad, bloquearon la avenida JB Lobos en el Puerto de Veracruz para exigir su pronta aparici\u00f3n con vida. La joven desapareci\u00f3 el 30 de noviembre despu\u00e9s de ir al centro de Veracruz a realizar unas compras en [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":126523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[],"class_list":["post-166219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=166219"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166219\/revisions"}],"predecessor-version":[{"id":166220,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/166219\/revisions\/166220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/126523"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=166219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=166219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=166219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}