{"id":165526,"date":"2024-11-22T11:10:49","date_gmt":"2024-11-22T17:10:49","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=165526"},"modified":"2024-11-22T11:10:51","modified_gmt":"2024-11-22T17:10:51","slug":"sheinbaum-responde-a-trudeau","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/11\/22\/sheinbaum-responde-a-trudeau\/","title":{"rendered":"Sheinbaum responde a Trudeau"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum asegur\u00f3 que el T-MEC es muy bueno para M\u00e9xico, Estados Unidos y Canad\u00e1, despu\u00e9s de que el primer ministro canadiense,&nbsp;Justin Trudeau&nbsp;, se\u00f1al\u00f3 que&nbsp;le gusta la idea de que el tratado comercial&nbsp;contin\u00fae, pero admiti\u00f3 que tendr\u00e1&nbsp;que considerar otras opciones dependiendo de las decisiones que tome M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la conferencia de prensa matutina en Palacio Nacional, la mandataria mexicana sostuvo que este tratado comercial &#8211; el cual se revisar\u00e1 el pr\u00f3ximo a\u00f1o &#8211; es complementario para el crecimiento de las econom\u00edas de los tres pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl tratado es muy bueno para los tres pa\u00edses, para los tres. Es muy bueno para Canad\u00e1, es muy bueno para Estados Unidos y es muy bueno para M\u00e9xico, lo dije desde que entr\u00e9 al gobierno.<br>En Norteam\u00e9rica este tratado hace que nos complementemos, que nuestras econom\u00edas crezcan, tengan desarrollo y bienestar, que finalmente es en lo que quiero que nosotros estamos planteando\u201d, destac\u00f3.<br>Desde el sal\u00f3n Tesorer\u00eda, la presidenta a\u00f1adi\u00f3 que habr\u00e1 que revisar a qu\u00e9 se refiere Justin Trudeau cuando habla de M\u00e9xico. Sostuvo que es importante que Estados Unidos y Canad\u00e1 tengan toda la informaci\u00f3n sobre las ventajas del tratado comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo platiqu\u00e9 en su momento con el primer ministro del Canad\u00e1. Hay que ver en particular a qu\u00e9 se refiere cuando se trata de M\u00e9xico, pero \u00e9l sabe que nuestra intenci\u00f3n es que siga el tratado.<br>\u201cY lo importante es que en Estados Unidos, en Canad\u00e1 y en M\u00e9xico tengamos toda la informaci\u00f3n de las ventajas que tiene el tratado, por ejemplo, para Estados Unidos, pero no solo se beneficia aqu\u00ed, o no solo en Canad\u00e1\u201d, apunt\u00f3.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/sheinbaum-a-trudeau-el-tratado-es-importante-para-mexico-canada-y-eu\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum asegur\u00f3 que el T-MEC es muy bueno para M\u00e9xico, Estados Unidos y Canad\u00e1, despu\u00e9s de que el primer ministro canadiense,&nbsp;Justin Trudeau&nbsp;, se\u00f1al\u00f3 que&nbsp;le gusta la idea de que el tratado comercial&nbsp;contin\u00fae, pero admiti\u00f3 que tendr\u00e1&nbsp;que considerar otras opciones dependiendo de las decisiones que tome M\u00e9xico. En la conferencia de prensa matutina [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":155745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[2801,162,3163],"class_list":["post-165526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-claudia-sheinbaum","tag-portada","tag-t-mec","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=165526"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165526\/revisions"}],"predecessor-version":[{"id":165528,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165526\/revisions\/165528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/155745"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=165526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=165526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=165526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}