{"id":165399,"date":"2024-11-20T13:18:42","date_gmt":"2024-11-20T19:18:42","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=165399"},"modified":"2024-11-20T13:18:44","modified_gmt":"2024-11-20T19:18:44","slug":"envia-sheinbaum-hoy-al-congreso-3-leyes-secundarias-a-la-reforma-judicial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/11\/20\/envia-sheinbaum-hoy-al-congreso-3-leyes-secundarias-a-la-reforma-judicial\/","title":{"rendered":"Env\u00eda Sheinbaum hoy al Congreso 3 leyes secundarias a la reforma judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La consejera Jur\u00eddica de la Presidencia, Ernestina Godoy, explic\u00f3 las reformas secundarias que el Ejecutivo enviar\u00e1 hoy a los senadores y diputados sobre la elecci\u00f3n de jueces, magistrados y ministros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hoy la Presidenta va a enviar tres iniciativas, la nueva ley org\u00e1nica del Poder Judicial, b\u00e1sicamente estamos, obviamente armonizando con la reforma, reorganizando la forma en la que tienen que trabajar sobre todo la Corte \u2014recuerden que van a ser nueve ministros ya no van a trabajar en salas, entonces era necesario que esta nueva ley org\u00e1nica se estableciera con claridad c\u00f3mo van a trabajar\u2014.&#8221;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En La Ma\u00f1anera del Pueblo desde Palacio Nacional, Godoy Ramos explic\u00f3 que las leyes secundarias son muy importantes porque se encuentran facultades del Tribunal de Justicia.<br><br>Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/sheinbaum-envia-congreso-3-leyes-secundarias-reforma-judicial\">Milenio<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consejera Jur\u00eddica de la Presidencia, Ernestina Godoy, explic\u00f3 las reformas secundarias que el Ejecutivo enviar\u00e1 hoy a los senadores y diputados sobre la elecci\u00f3n de jueces, magistrados y ministros. &#8220;Hoy la Presidenta va a enviar tres iniciativas, la nueva ley org\u00e1nica del Poder Judicial, b\u00e1sicamente estamos, obviamente armonizando con la reforma, reorganizando la forma [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":85267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801,348,162],"class_list":["post-165399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","tag-congreso","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=165399"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165399\/revisions"}],"predecessor-version":[{"id":165402,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/165399\/revisions\/165402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/85267"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=165399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=165399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=165399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}