{"id":163942,"date":"2024-11-03T07:00:00","date_gmt":"2024-11-03T13:00:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=163942"},"modified":"2024-11-03T00:04:34","modified_gmt":"2024-11-03T06:04:34","slug":"ministro-gonzalez-alcantara-pide-a-sheinbaum-reflexionar-por-reforma-judicial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/11\/03\/ministro-gonzalez-alcantara-pide-a-sheinbaum-reflexionar-por-reforma-judicial\/","title":{"rendered":"Ministro Gonz\u00e1lez Alc\u00e1ntara pide a Sheinbaum reflexionar por reforma judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El ministro\u00a0<strong>Juan Luis Gonz\u00e1lez Alc\u00e1ntara<\/strong>-Carranc\u00e1 pidi\u00f3 a la presidenta\u00a0<strong>Claudia Sheinbaum Pardo<\/strong>\u00a0reflexionar sobre el proyecto de resoluci\u00f3n que present\u00f3 y cuya discusi\u00f3n en la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) ser\u00e1 el pr\u00f3ximo 5 de noviembre; mismo que, entre otras cosas, propone\u00a0<strong>invalidar parte de la Reforma Judicial<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista con la periodista Azucena Uresti para&nbsp;<em>Radio F\u00f3rmula,&nbsp;<\/em>el togado se\u00f1al\u00f3 que la mandataria federal tiene estos d\u00edas para reflexionar<em>&nbsp;<\/em>sobre&nbsp;<strong>cu\u00e1les ser\u00edan las consecuencias<\/strong>&nbsp;en caso de que el proyecto sea aprobado y ni el Legislativo ni el Ejecutivo acaten la&nbsp;<strong>resoluci\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo creo que la presidenta tendr\u00e1 que reflexionar, tiene los pr\u00f3ximos d\u00edas para hacerlo; estos d\u00edas que son tan importantes para el pueblo de M\u00e9xico, reflexionar cu\u00e1les son las consecuencias y&nbsp;<strong>buscar un escenario alternativo<\/strong>\u201d, declar\u00f3 durante la ma\u00f1ana del 1 de noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que el Poder Judicial dicta las resoluciones y no tiene la fuerza militar ni policiaca para imponer su determinaci\u00f3n, por lo que llam\u00f3 a la\u00a0<strong>prudencia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2024\/11\/02\/ministro-gonzalez-alcantara-pide-a-sheinbaum-reflexionar-por-reforma-judicial-el-pais-necesita-tranquilidad\/?utm_cmp_rs=ifc%3AFC_pkPMe9MoSnmEyVpsHRvb5A\">Infobae<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro\u00a0Juan Luis Gonz\u00e1lez Alc\u00e1ntara-Carranc\u00e1 pidi\u00f3 a la presidenta\u00a0Claudia Sheinbaum Pardo\u00a0reflexionar sobre el proyecto de resoluci\u00f3n que present\u00f3 y cuya discusi\u00f3n en la Suprema Corte de Justicia de la Naci\u00f3n (SCJN) ser\u00e1 el pr\u00f3ximo 5 de noviembre; mismo que, entre otras cosas, propone\u00a0invalidar parte de la Reforma Judicial. En entrevista con la periodista Azucena Uresti [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":161936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[2801],"class_list":["post-163942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-claudia-sheinbaum","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=163942"}],"version-history":[{"count":6,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163942\/revisions"}],"predecessor-version":[{"id":163950,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163942\/revisions\/163950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/161936"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=163942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=163942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=163942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}