{"id":163281,"date":"2024-10-25T11:59:47","date_gmt":"2024-10-25T17:59:47","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=163281"},"modified":"2024-10-25T11:59:49","modified_gmt":"2024-10-25T17:59:49","slug":"reconoce-y-enaltece-imss-veracruz-norte-a-medicas-y-medicos-en-su-dia","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/10\/25\/reconoce-y-enaltece-imss-veracruz-norte-a-medicas-y-medicos-en-su-dia\/","title":{"rendered":"Reconoce y enaltece\u00a0IMSS Veracruz Norte\u00a0a M\u00e9dicas\u00a0y M\u00e9dicos\u00a0en su\u00a0d\u00eda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Instituto Mexicano del Seguro Social (IMSS) en Veracruz Norte reconoce y enaltece a las y los m\u00e9dicos en su d\u00eda, quienes cotidianamente demuestran sus&nbsp;habilidades&nbsp;de competencia cl\u00ednicapara brindar la&nbsp;atenci\u00f3n integral y continua a todo aquel paciente que los requiera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, se entregaron 37 reconocimientos a personal M\u00e9dico y de Estomatolog\u00eda, por su desempe\u00f1o sobresaliente durante el ejercicio 2023, mismos que fueron entregados por el titular de la&nbsp;representaci\u00f3n del IMSS en Veracruz Norte, doctor Jorge Mart\u00ednez Torres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su oportunidad, Mart\u00ednez Torres apunt\u00f3 \u201cen el IMSS, a lo largo de sus 81 a\u00f1os de existencia, los m\u00e9dicos han sido un factor determinante en la transformaci\u00f3n y evoluci\u00f3n de sistema de salud, para garantizar el derecho a la atenci\u00f3n de calidad,&nbsp;por lo que&nbsp;reconocemos la incansable labor que realizan en beneficio de nuestros derechohabientes&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar, que posterior a la entrega de reconocimientos,&nbsp;se&nbsp;imparti\u00f3 el curso&nbsp;sobre el&nbsp;\u201cFortalecimiento del manejo y control metab\u00f3lico en el paciente con diabetes mellitus e hipertensi\u00f3n arterial\u201d, cuyo objetivo, es el de&nbsp;reducir el riesgo de hospitalizaci\u00f3n por complicaciones cardiovasculares y&nbsp;la discapacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, el Seguro Social refrenda su compromiso con la mejora continua del&nbsp;perfil profesional del m\u00e9dico,&nbsp;en congruencia con la \u00e9tica m\u00e9dica, responsabilidad, comunicaci\u00f3n y habilidades de competencia cl\u00ednica para brindar la atenci\u00f3n integral a&nbsp;todo tipo de pacientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Mexicano del Seguro Social (IMSS) en Veracruz Norte reconoce y enaltece a las y los m\u00e9dicos en su d\u00eda, quienes cotidianamente demuestran sus&nbsp;habilidades&nbsp;de competencia cl\u00ednicapara brindar la&nbsp;atenci\u00f3n integral y continua a todo aquel paciente que los requiera. Durante el evento, se entregaron 37 reconocimientos a personal M\u00e9dico y de Estomatolog\u00eda, por su desempe\u00f1o [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":163286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[1687],"class_list":["post-163281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-imss-veracruz-norte","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=163281"}],"version-history":[{"count":2,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163281\/revisions"}],"predecessor-version":[{"id":163283,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/163281\/revisions\/163283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/163286"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=163281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=163281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=163281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}