{"id":162880,"date":"2024-10-20T19:51:00","date_gmt":"2024-10-21T01:51:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=162880"},"modified":"2024-10-21T07:52:13","modified_gmt":"2024-10-21T13:52:13","slug":"derrumban-vientos-cimbra-en-plaza-aquarium","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/10\/20\/derrumban-vientos-cimbra-en-plaza-aquarium\/","title":{"rendered":"Derrumban vientos cimbra en Plaza Aquarium"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz, Ver. El fuerte temporal que azot\u00f3 la ciudad de Veracruz este fin de semana, caus\u00f3 el colapso de una estructura de madera en la parte trasera de Plaza Aquarium. La Procuradur\u00eda Estatal de Protecci\u00f3n al Medio Ambiente (PMA) inform\u00f3 que las fuertes rachas de viento, que alcanzaron los 70 kil\u00f3metros por hora, provocaron el derrumbe de la cimbra de madera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afortunadamente, no se reportaron lesionados ni da\u00f1os materiales significativos en el per\u00edmetro de la plaza comercial. La estructura afectada se encontraba en proceso de construcci\u00f3n y era una cimbra provisional de madera, ubicada en la parte trasera del Aquarium, expuesta directamente a los vientos del norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa encargada de la obra asegur\u00f3 que reanudar\u00e1 los trabajos una vez que hayan pasado los efectos del frente fr\u00edo que afecta a la conurbaci\u00f3n Veracruz-Boca del R\u00edo. El objetivo es completar el proyecto y ofrecer a los veracruzanos y turistas el Aquarium m\u00e1s moderno y completo del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La PMA y las autoridades locales contin\u00faan monitoreando la situaci\u00f3n y trabajando para garantizar la seguridad y calidad de la obra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Veracruz, Ver. El fuerte temporal que azot\u00f3 la ciudad de Veracruz este fin de semana, caus\u00f3 el colapso de una estructura de madera en la parte trasera de Plaza Aquarium. La Procuradur\u00eda Estatal de Protecci\u00f3n al Medio Ambiente (PMA) inform\u00f3 que las fuertes rachas de viento, que alcanzaron los 70 [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":62142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[31092],"class_list":["post-162880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-plaza-aquarium","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=162880"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162880\/revisions"}],"predecessor-version":[{"id":162881,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162880\/revisions\/162881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/62142"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=162880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=162880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=162880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}