{"id":162065,"date":"2024-10-10T14:49:24","date_gmt":"2024-10-10T20:49:24","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=162065"},"modified":"2024-10-10T14:49:26","modified_gmt":"2024-10-10T20:49:26","slug":"exigen-a-quienes-hacen-kayak-y-paddle-respetar-regulaciones-ambientales-en-la-isla-de-sacrificios","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/10\/10\/exigen-a-quienes-hacen-kayak-y-paddle-respetar-regulaciones-ambientales-en-la-isla-de-sacrificios\/","title":{"rendered":"Exigen a quienes hacen kayak y paddle respetar regulaciones ambientales en la Isla de Sacrificios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director del Parque Nacional Sistema Arrecifal Veracruzano, Jos\u00e9 Carlos Piza\u00f1a Soto, hizo un llamado a quienes hacen kayak y paddle para que respeten las regulaciones ambientales en la Isla de Sacrificios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Piza\u00f1a Soto solicit\u00f3 que los visitantes no bajen a la playa de la isla, ya que esto est\u00e1 prohibido y puede da\u00f1ar los h\u00e1bitats de especies protegidas, como tortugas y aves que anidan en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos han dicho que llegan en kayak y se bajan y andan ah\u00ed pero la isla est\u00e1 cerrada para esa actividad porque en la zona hay anidaci\u00f3n de tortugas marinas y aves. Hacerles un llamado a quienes hacen kayak a que le den la vuelta pero no pueden bajarse a la isla\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Isla de Sacrificios es un sitio de valor ecol\u00f3gico y cultural, y es importante que los visitantes sean conscientes de su impacto en el medio ambiente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Isla de Sacrificios est\u00e1 cerrada a la visita desde 1982, solo se permiten actividades de seguridad mar\u00edtima. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso hay instalaciones de Asipona, Capitania del Puerto y hay un obelisco franc\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEmpez\u00f3 a aumentar la actividad de kayak y paddle y a partir de ah\u00ed se ha incrementado. No ten\u00edamos registros pero hace unos meses comenzaron a darse las quejas de que van a dar la vuelta pero hab\u00eda gente en la playa entonces se les est\u00e1 llamando la atenci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Parque Nacional Sistema Arrecifal Veracruzano cuenta con 65 mil hect\u00e1reas de \u00e1rea marina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener un permiso de actividad tur\u00edstica se debe estar registrado ante Capitan\u00eda del Puerto y las embarcaciones deben estar especificadas para turismo n\u00e1utico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias El director del Parque Nacional Sistema Arrecifal Veracruzano, Jos\u00e9 Carlos Piza\u00f1a Soto, hizo un llamado a quienes hacen kayak y paddle para que respeten las regulaciones ambientales en la Isla de Sacrificios. Piza\u00f1a Soto solicit\u00f3 que los visitantes no bajen a la playa de la isla, ya que esto est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":162066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[8941,6295,11726],"class_list":["post-162065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-invasion","tag-isla-de-sacrificios","tag-parque-nacional-sistema-arrecifal-veracruzano","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=162065"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162065\/revisions"}],"predecessor-version":[{"id":162067,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162065\/revisions\/162067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/162066"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=162065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=162065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=162065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}