{"id":162046,"date":"2024-10-10T13:49:04","date_gmt":"2024-10-10T19:49:04","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=162046"},"modified":"2024-10-10T13:49:06","modified_gmt":"2024-10-10T19:49:06","slug":"consul-de-mexico-en-orlando-da-informe-tras-el-paso-del-huracan-milton-en-florida","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/10\/10\/consul-de-mexico-en-orlando-da-informe-tras-el-paso-del-huracan-milton-en-florida\/","title":{"rendered":"C\u00f3nsul de M\u00e9xico en Orlando da informe tras el paso del hurac\u00e1n Milton en Florida"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por el momento&nbsp;<strong>no se reportan mexicanos fallecidos ni lesionados,<\/strong>&nbsp;tras el paso del Hurac\u00e1n Milton en Florida, Estados Unidos, inform\u00f3 el c\u00f3nsul de M\u00e9xico en Orlando, Juan Sabines Guerrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, hizo un llamado la comunidad mexicana, a resguardarse ante el impacto del fen\u00f3meno natural en Florida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi te encuentras en un albergue \/ shelter, informa a tu Consulado para que podamos brindarte asistencia consular tan pronto como las condiciones meteorol\u00f3gicas lo permitan\u201d, manifest\u00f3 el c\u00f3nsul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En redes sociales expuso que en caso de emergencia, llamen al 911 y a los que decidieron quedarse en casa\u00a0<strong>les pidi\u00f3 refugiarse en un lugar seguro.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n a\u00f1adi\u00f3 los tel\u00e9fonos de emergencia consular a los que se pueden contactar ante cualquier eventualidad. Consulado de M\u00e9xico en Orlando: 407 409 4209, y Consulado de M\u00e9xico en Miami: 305 979 1534.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del n\u00famero telef\u00f3nico del Centro de Informaci\u00f3n y Asistencia a Personas Mexicanas: 520 623 7874.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda de ayer, la Secretar\u00eda de Relaciones Exteriores (<strong>SRE<\/strong>) de M\u00e9xico inform\u00f3 que los consulados en&nbsp;<strong>Miami<\/strong>&nbsp;y&nbsp;<strong>Orlando<\/strong>&nbsp;activaron el&nbsp;<strong>protocolo de emergencia<\/strong>&nbsp;por desastres naturales desde el 5 de octubre, ante la inminente llegada del&nbsp;<strong>hurac\u00e1n Milton<\/strong>&nbsp;a las costas de Florida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este protocolo, explic\u00f3, est\u00e1 dise\u00f1ado para proteger a la comunidad mexicana residente en las zonas m\u00e1s afectadas, principalmente en el centro y noreste del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mi\u00e9rcoles, el\u00a0<strong>hurac\u00e1n Milton<\/strong>\u00a0perdi\u00f3 intensidad y baj\u00f3 de categor\u00eda, de 4 a 3, con vientos m\u00e1ximos sostenidos de 125 millas por hora (205 kil\u00f3metros), camino de la costa oeste de\u00a0<strong>Florida.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/mexico\/2024\/10\/10\/no-hay-mexicanos-muertos-por-el-paso-del-huracan-milton-en-florida-informa-consul\/\" data-type=\"link\" data-id=\"https:\/\/www.infobae.com\/mexico\/2024\/10\/10\/no-hay-mexicanos-muertos-por-el-paso-del-huracan-milton-en-florida-informa-consul\/\">Infobae<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por el momento&nbsp;no se reportan mexicanos fallecidos ni lesionados,&nbsp;tras el paso del Hurac\u00e1n Milton en Florida, Estados Unidos, inform\u00f3 el c\u00f3nsul de M\u00e9xico en Orlando, Juan Sabines Guerrero. Sin embargo, hizo un llamado la comunidad mexicana, a resguardarse ante el impacto del fen\u00f3meno natural en Florida. \u201cSi te encuentras en un albergue \/ shelter, informa [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":162047,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[31019,292,12461],"class_list":["post-162046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-huracan-milton","tag-mexico","tag-orlando","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=162046"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162046\/revisions"}],"predecessor-version":[{"id":162048,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/162046\/revisions\/162048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/162047"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=162046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=162046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=162046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}