{"id":15985,"date":"2021-06-11T19:17:42","date_gmt":"2021-06-12T00:17:42","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=15985"},"modified":"2021-06-11T19:17:43","modified_gmt":"2021-06-12T00:17:43","slug":"firman-imss-y-consejo-de-la-judicatura-federal-convenio-para-el-sistema-de-justicia-laboral","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/06\/11\/firman-imss-y-consejo-de-la-judicatura-federal-convenio-para-el-sistema-de-justicia-laboral\/","title":{"rendered":"Firman IMSS y Consejo de la Judicatura Federal convenio para el Sistema de Justicia Laboral"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Instituto Mexicano del Seguro Social (IMSS) y el Consejo de la Judicatura Federal (CJF) firmaron un Convenio para el Sistema de Justicia Laboral, el cual permitir\u00e1 abatir el rezago de juicios y evitar conflictos individuales de Seguridad Social ante los nuevos \u00f3rganos jurisdiccionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n del director general del IMSS, Maestro Zo\u00e9 Robledo, el director Jur\u00eddico, Antonio P\u00e9rez Fonticoba, se\u00f1al\u00f3 que el Instituto celebra la firma de este Convenio que pone a disposici\u00f3n de los tribunales la informaci\u00f3n institucional en materia laboral y de seguridad social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto realizado en las instalaciones del Instituto del Fondo Nacional de la Vivienda para los Trabajadores (INFONAVIT), explic\u00f3 que con esto se permitir\u00e1 el acceso a las bases de datos del IMSS para consultar datos p\u00fablicos que actualmente son utilizados en la defensa de los juicios: N\u00famero de Seguridad Social, registro laboral del trabajador, semanas cotizadas, entre otros, con la finalidad de \u201cgarantizar el derecho de acceso a una justicia \u00e1gil, sencilla, efectiva y transparente\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cEstamos convencidos que cuando ocurra este tipo de cooperaci\u00f3n y reconocimiento entre las instituciones, siempre se obtienen los mejores resultados para nuestro pa\u00eds y desde luego, para la clase trabajadora que demanda justicia expedita y \u00e1gil\u201d<\/em>, dijo.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el Secretario General de la Presidencia del CJF, Carlos Antonio Alp\u00edzar, se\u00f1al\u00f3 que con esta herramienta tecnol\u00f3gica se lograr\u00e1 hacer la justicia laboral m\u00e1s accesible a los justiciables, al permitir que se transite a un juicio en l\u00ednea.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cEsta colaboraci\u00f3n fortalece la instancia de hacer la justicia en materia laboral m\u00e1s \u00e1gil, eficiente y m\u00e1s expedita; facilitando los procesos y procedimientos de los operadores jur\u00eddicos ante la posibilidad de consultar de forma inmediata la informaci\u00f3n mediante la plataforma\u201d<\/em>, indic\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Asistieron Carlos Mart\u00ednez Vel\u00e1zquez, director general del INFONAVIT; Jos\u00e9 Fernando Franco Gonz\u00e1lez Salas, Ministro de la Suprema Corte de Justicia de la Naci\u00f3n; Alfredo Dom\u00ednguez Marrufo, director general del Centro Federal de Conciliaci\u00f3n y Registro Laboral de la Secretar\u00eda del Trabajo y de Previsi\u00f3n Social (STPS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Sergio Javier Molina Mart\u00ednez, consejero de la Judicatura Federal; y H\u00e9ctor Paniagua Robles, titular de la Unidad de Implementaci\u00f3n de la Reforma en Materia de Justicia Laboral del Consejo de la Judicatura Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Mexicano del Seguro Social (IMSS) y el Consejo de la Judicatura Federal (CJF) firmaron un Convenio para el Sistema de Justicia Laboral, el cual permitir\u00e1 abatir el rezago de juicios y evitar conflictos individuales de Seguridad Social ante los nuevos \u00f3rganos jurisdiccionales. En representaci\u00f3n del director general del IMSS, Maestro Zo\u00e9 Robledo, el [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15990,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[2529,365,1643,4375],"class_list":["post-15985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-consejo-de-la-judicatura-federal","tag-imss","tag-instituto-mexicano-del-seguro-social","tag-sistema-de-justicia-laboral","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/15985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=15985"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/15985\/revisions"}],"predecessor-version":[{"id":15991,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/15985\/revisions\/15991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/15990"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=15985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=15985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=15985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}