{"id":157838,"date":"2024-08-21T09:56:10","date_gmt":"2024-08-21T15:56:10","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=157838"},"modified":"2024-08-21T10:09:55","modified_gmt":"2024-08-21T16:09:55","slug":"piden-empresarios-de-eu-a-biden-plantear-a-sheinbaum-posibles-violaciones-al-t-mec-con-reforma-judicial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/08\/21\/piden-empresarios-de-eu-a-biden-plantear-a-sheinbaum-posibles-violaciones-al-t-mec-con-reforma-judicial\/","title":{"rendered":"Piden empresarios de EU a Biden plantear a Sheinbaum posibles violaciones al T-MEC con reforma judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Asociaciones, consejos, coaliciones y organizaciones de la iniciativa privada de Estados Unidos del sector m\u00e9dico, qu\u00edmico, energ\u00e9tico, industrial, tecnolog\u00edas de la informaci\u00f3n, servicios y minero, entre otros expresaron, al gobierno del estadounidense,&nbsp;<strong>Joe Biden<\/strong>, su preocupaci\u00f3n por el<strong>&nbsp;paquete de reformas<\/strong>&nbsp;que est\u00e1 por aprobar el congreso mexicano.<\/p>\n\n\n\n<p class=\"sc__font-paragraph wp-block-paragraph\">El sector empresarial estadounidense dijo que las iniciativas incluyen cambios constitucionales que son contrarios al Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (<strong>T-MEC<\/strong>).<\/p>\n\n\n\n<p class=\"sc__font-paragraph wp-block-paragraph\">Por lo que, piden al gobierno estadounidense compartir con la presidenta electa&nbsp;<strong>Claudia Sheinbaum<\/strong>&nbsp;las preocupaciones y recomendarle un proceso m\u00e1s lento y con mayor discusi\u00f3n sobre los cambios constitucionales.<\/p>\n\n\n\n<p class=\"sc__font-paragraph wp-block-paragraph\">En una carta dirigida al secretario de Estado del vecino pa\u00eds del Norte fechada el 19 de agosto,&nbsp;<strong>Antony Blinken<\/strong>, las nueve organizaciones dijeron que \u201cvarias de estas enmiendas parecen violar las obligaciones de M\u00e9xico bajo el T-MEC. Las enmiendas tambi\u00e9n incluyen una propuesta para destituir a todos los jueces y reemplazarlos mediante elecci\u00f3n popular, lo que plantea riesgos importantes para el derecho fundamental y para la administraci\u00f3n de justicia en M\u00e9xico\u201d.<\/p>\n\n\n\n<p class=\"sc__font-paragraph wp-block-paragraph\">El cumplimiento del T-MEC sin un sistema judicial justo se someter\u00e1 a una tensi\u00f3n adicional, adem\u00e1s de que hay otras iniciativas de cambio constitucional que son contrarias a los&nbsp;<strong>compromisos de M\u00e9xico<\/strong>&nbsp;en el tratado comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/cartera\/empresarios-de-eu-piden-a-biden-plantear-a-sheinbaum-posibles-violaciones-al-t-mec-con-reforma-judicial\/\">El Universal<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asociaciones, consejos, coaliciones y organizaciones de la iniciativa privada de Estados Unidos del sector m\u00e9dico, qu\u00edmico, energ\u00e9tico, industrial, tecnolog\u00edas de la informaci\u00f3n, servicios y minero, entre otros expresaron, al gobierno del estadounidense,&nbsp;Joe Biden, su preocupaci\u00f3n por el&nbsp;paquete de reformas&nbsp;que est\u00e1 por aprobar el congreso mexicano. El sector empresarial estadounidense dijo que las iniciativas incluyen cambios [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":64990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[181],"tags":[2801,182,162,3163],"class_list":["post-157838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-claudia-sheinbaum","tag-joe-biden","tag-portada","tag-t-mec","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/157838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=157838"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/157838\/revisions"}],"predecessor-version":[{"id":157839,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/157838\/revisions\/157839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/64990"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=157838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=157838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=157838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}