{"id":156108,"date":"2024-07-29T13:30:26","date_gmt":"2024-07-29T19:30:26","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=156108"},"modified":"2024-07-29T13:30:29","modified_gmt":"2024-07-29T19:30:29","slug":"gobierno-de-mexico-sin-idea-del-motivo-que-tuvo-chapito-para-entregarse-a-eu-rosa-icela-rodriguez-2","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/07\/29\/gobierno-de-mexico-sin-idea-del-motivo-que-tuvo-chapito-para-entregarse-a-eu-rosa-icela-rodriguez-2\/","title":{"rendered":"Gobierno de M\u00e9xico, sin idea del motivo que tuvo Chapito para entregarse a EU: Rosa Icela Rodr\u00edguez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Rosa Icela Rodr\u00edguez Vel\u00e1zquez<\/strong>, secretaria de Seguridad (<strong>SSPC<\/strong>), reconoci\u00f3 que el gobierno mexicano no tiene idea del motivo que tuvo Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo de \u201cEl Chapo\u201d para entregarse a las autoridades de Estados Unidos la semana pasada, junto con<strong>\u00a0Ismael \u201cMayo\u201d Zambada<\/strong>, a Estados Unidos, y se\u00f1al\u00f3 que es parte de las investigaciones que realiza la FGR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En\u00a0<strong>conferencia de prensa del presidente L\u00f3pez Obrador<\/strong>, la secretaria se\u00f1al\u00f3 que en las investigaciones que se llevan a cabo por estos hechos por parte de la FGR tambi\u00e9n est\u00e1 el origen del vuelo, as\u00ed como la identidad del piloto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201c\u00bfTiene una idea de por qu\u00e9 se rindi\u00f3\u00a0<strong>Joaqu\u00edn Guzm\u00e1n L\u00f3pez<\/strong>?\u201d, se le pregunt\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cNo, es parte de la investigaci\u00f3n. Nosotros estamos nosotros hoy dando un reporte que nos da la Embajada de Estados Unidos a la FGR, y a todos los integrantes del gabinete de seguridad. Entonces lo que estamos haciendo exclusivamente es transmitirles, informarles a ustedes qu\u00e9 es lo que hay hasta el momento.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cFalta todav\u00eda alguna informaci\u00f3n que consideren tambi\u00e9n en esta investigaci\u00f3n proporcionar las autoridades de Estados Unidos, por lo pronto enumeramos estos siete puntos, textualmente es lo que ellos informan\u201d, dijo.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201c\u00bfSi el vuelo sali\u00f3 de Hermosillo o no como se coment\u00f3 el vienes? Si nos pudieran aclarar, porque el piloto ha declarado en Estados Unidos en medios que no fue \u00e9l, que no fue en este vuelo, que hubo una equivocaci\u00f3n, un error por parte de M\u00e9xico? Si nos pueden aclarar \u201d, se le insisti\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cS\u00ed, efectivamente como dec\u00eda anteriormente es parte de la investigaci\u00f3n que la FGR est\u00e1 haciendo. Va hacer todas las consideraci\u00f3n de todas las entidades o aeropuertos, personal que hayan estado, digamos como testigos en este caso. Eso es parte de las investigaciones de la FGR\u201d.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEntonces, \u00bfaun no se descarta que sea este vuelo de Hermosillo?\u201d, se le insisti\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/gobierno-de-mexico-sin-idea-del-motivo-que-tuvo-chapito-para-entregarse-a-eu-rosa-icela-rodriguez\/\"> El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rosa Icela Rodr\u00edguez Vel\u00e1zquez, secretaria de Seguridad (SSPC), reconoci\u00f3 que el gobierno mexicano no tiene idea del motivo que tuvo Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo de \u201cEl Chapo\u201d para entregarse a las autoridades de Estados Unidos la semana pasada, junto con\u00a0Ismael \u201cMayo\u201d Zambada, a Estados Unidos, y se\u00f1al\u00f3 que es parte de las investigaciones que realiza [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":10440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[30562,5683,12610],"class_list":["post-156108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-chapito","tag-gobierno-de-mexico","tag-rosa-icela-rodriguez","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/156108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=156108"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/156108\/revisions"}],"predecessor-version":[{"id":156109,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/156108\/revisions\/156109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/10440"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=156108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=156108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=156108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}