{"id":150878,"date":"2024-06-03T10:16:00","date_gmt":"2024-06-03T16:16:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=150878"},"modified":"2024-06-03T10:16:02","modified_gmt":"2024-06-03T16:16:02","slug":"jornada-electoral-se-desarrollo-de-manera-pacifica-con-incidentes-minimos-rosa-icela-rodriguez","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2024\/06\/03\/jornada-electoral-se-desarrollo-de-manera-pacifica-con-incidentes-minimos-rosa-icela-rodriguez\/","title":{"rendered":"Jornada electoral se desarroll\u00f3 de manera pac\u00edfica, con incidentes m\u00ednimos: Rosa Icela Rodr\u00edguez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tras celebrarse este domingo 2 de junio las elecciones en M\u00e9xico, la secretaria de Seguridad, Rosa Icela Rodr\u00edguez, afirm\u00f3 que \u201cla jornada electoral se desarroll\u00f3 de manera pac\u00edfica, con incidentes m\u00ednimos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la conferencia ma\u00f1anera del presidente Andr\u00e9s Manuel L\u00f3pez Obrador de este lunes 3 de junio en Palacio Nacional, la secretaria de Seguridad destac\u00f3 una buena coordinaci\u00f3n entre el Instituto Nacional Electoral (INE), el gabinete de seguridad y los gobiernos locales.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cFue una fiesta c\u00edvica en paz y con problemas menores. Fue una jornada hist\u00f3rica y ejemplar\u201d, declar\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Reiter\u00f3 que los comicios de ayer transcurrieron con tranquilidad, \u201clo que permiti\u00f3 que millones de mexicanos salieran a votar de manera libre, directa y secreta\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante L\u00f3pez Obrador, la secretaria de Seguridad agradeci\u00f3 a los soldados, marinos, guardias nacionales, polic\u00edas estatales, municipales, y ministeriales, as\u00ed como la FGR y fiscal\u00edas de los estados \u201cpor todo su empe\u00f1o\u201d para lograr el buen desempe\u00f1o del proceso electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n agradeci\u00f3 a los gobiernos locales y a la ciudadan\u00eda que particip\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/rosa-icela-rodriguez-jornada-electoral-se-desarrollo-de-manera-pacifica-con-incidentes-minimos\/\" data-type=\"link\" data-id=\"https:\/\/www.eluniversal.com.mx\/nacion\/rosa-icela-rodriguez-jornada-electoral-se-desarrollo-de-manera-pacifica-con-incidentes-minimos\/\"> El Universal<\/a><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras celebrarse este domingo 2 de junio las elecciones en M\u00e9xico, la secretaria de Seguridad, Rosa Icela Rodr\u00edguez, afirm\u00f3 que \u201cla jornada electoral se desarroll\u00f3 de manera pac\u00edfica, con incidentes m\u00ednimos\u201d. En la conferencia ma\u00f1anera del presidente Andr\u00e9s Manuel L\u00f3pez Obrador de este lunes 3 de junio en Palacio Nacional, la secretaria de Seguridad destac\u00f3 [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":46827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[209,12610],"class_list":["post-150878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-elecciones","tag-rosa-icela-rodriguez","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/150878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=150878"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/150878\/revisions"}],"predecessor-version":[{"id":150879,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/150878\/revisions\/150879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/46827"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=150878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=150878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=150878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}