{"id":128753,"date":"2023-11-11T15:49:00","date_gmt":"2023-11-11T21:49:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=128753"},"modified":"2023-11-12T07:51:08","modified_gmt":"2023-11-12T13:51:08","slug":"sentenciado-a-20-anos-de-prision-como-responsable-del-delito-de-homicidio-doloso-calificado","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/11\/11\/sentenciado-a-20-anos-de-prision-como-responsable-del-delito-de-homicidio-doloso-calificado\/","title":{"rendered":"Sentenciado a 20 a\u00f1os de prisi\u00f3n como responsable del delito de homicidio doloso calificado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Zongolica, Ver.- La Fiscal\u00eda Regional C\u00f3rdoba logr\u00f3 sentencia condenatoria de 20 a\u00f1os de prisi\u00f3n en contra de Mariano \u201cN\u201d como responsable del delito de homicidio doloso calificado en agravio de una v\u00edctima identificada con las iniciales H.M.N.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los hechos ocurrieron el 11 de junio del 2022, en la localidad Atzingo, perteneciente al municipio de Texhuac\u00e1n cuando accion\u00f3 un arma de fuego en contra de la v\u00edctima y la priv\u00f3 de la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez adem\u00e1s de dictar sentencia, suspendi\u00f3 sus derechos civiles y pol\u00edticos y estableci\u00f3 un pago por concepto de reparaci\u00f3n del da\u00f1o, dentro del proceso penal 24\/2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zongolica, Ver.- La Fiscal\u00eda Regional C\u00f3rdoba logr\u00f3 sentencia condenatoria de 20 a\u00f1os de prisi\u00f3n en contra de Mariano \u201cN\u201d como responsable del delito de homicidio doloso calificado en agravio de una v\u00edctima identificada con las iniciales H.M.N. Los hechos ocurrieron el 11 de junio del 2022, en la localidad Atzingo, perteneciente al municipio de Texhuac\u00e1n [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":128754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[4564,28237,2065],"class_list":["post-128753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-homicidio","tag-sentenciado","tag-zongolica","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/128753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=128753"}],"version-history":[{"count":2,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/128753\/revisions"}],"predecessor-version":[{"id":128756,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/128753\/revisions\/128756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/128754"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=128753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=128753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=128753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}