{"id":122193,"date":"2023-09-23T14:06:03","date_gmt":"2023-09-23T19:06:03","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=122193"},"modified":"2023-09-23T14:06:04","modified_gmt":"2023-09-23T19:06:04","slug":"llega-exposicion-fotografica-200-anos-del-heroico-colegio-militar","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/09\/23\/llega-exposicion-fotografica-200-anos-del-heroico-colegio-militar\/","title":{"rendered":"Llega exposici\u00f3n fotogr\u00e1fica \u2018200 a\u00f1os del Heroico Colegio Militar\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3mo parte del 200 aniversario del Heroico Colegio Militar, personal de la Secretar\u00eda de la Defensa Nacional (Sedena), mont\u00f3 una exposici\u00f3n fotogr\u00e1fica en la explanada del Acuario de Veracruz,  ubicado en el Blvd. Manuel Avila Camacho del municipio de Veracruz. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El material gr\u00e1fico consta de 8 piezas y ser\u00e1 exhibido por \u00fanico d\u00eda en el puerto de Veracruz, este s\u00e1bado 23 de septiembre en un horario de 10 de la ma\u00f1ana hasta las 2pm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las fotograf\u00edas en diversos tama\u00f1os retratan los adiestramientos, desfiles y las misiones fuera del plantel. Pero tambi\u00e9n presentan a personajes que siendo militares representaron con destacados resultados a M\u00e9xico en Olimpiadas, e incluso al cantante y actor Jorge Negrete, que caus\u00f3 alta al Colegio en el que lleg\u00f3 a Teniente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los momentos preservados a trav\u00e9s de fotograf\u00edas fueron capturados por personal del \u00e1rea de comunicaci\u00f3n y difusi\u00f3n de la Secretar\u00eda de la Defensa Nacional (SEDENA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta exposici\u00f3n estar\u00e1 a la vista de los ciudadanos y visitantes que lleguen a este municipio tur\u00edstico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe hacer menci\u00f3n que la exposici\u00f3n es itinerante, por lo que estar\u00e1 pr\u00f3ximamente en Xalapa, Perote y Martinez de la Torre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pasados d\u00edas lleg\u00f3 al evento deportivo denominado &#8220;Veracruz 2023 WorldTaekwondoChampionships&#8221; que se celebra en las instalaciones del World Trad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias C\u00f3mo parte del 200 aniversario del Heroico Colegio Militar, personal de la Secretar\u00eda de la Defensa Nacional (Sedena), mont\u00f3 una exposici\u00f3n fotogr\u00e1fica en la explanada del Acuario de Veracruz, ubicado en el Blvd. Manuel Avila Camacho del municipio de Veracruz. El material gr\u00e1fico consta de 8 piezas y ser\u00e1 exhibido [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":122194,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[27433,20505],"class_list":["post-122193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-200-anos-del-heroico-colegio-militar","tag-exposicion-fotografica","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/122193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=122193"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/122193\/revisions"}],"predecessor-version":[{"id":122195,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/122193\/revisions\/122195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/122194"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=122193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=122193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=122193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}