{"id":121406,"date":"2023-09-17T17:40:00","date_gmt":"2023-09-17T22:40:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=121406"},"modified":"2023-09-18T06:42:47","modified_gmt":"2023-09-18T11:42:47","slug":"se-responsabiliza-trump-de-acciones-tras-perder-elecciones-en-2020","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/09\/17\/se-responsabiliza-trump-de-acciones-tras-perder-elecciones-en-2020\/","title":{"rendered":"Se responsabiliza Trump de acciones tras perder elecciones en 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El expresidente estadounidense\u00a0<strong>Donald Trump,<\/strong>\u00a0quien enfrenta diversos procesos penales, incluyendo dos por sus intentos de revertir los resultados de las elecciones de 2020, en las que perdi\u00f3 ante\u00a0<strong>Joe Biden<\/strong>,\u00a0<strong>asegur\u00f3 que fue &#8220;mi decisi\u00f3n&#8221; las acciones emprendidas entonces.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una entrevista con la periodista Kristen Welker para el programa Meet the Press, de la cadena NBC, transmitida esta ma\u00f1ana,&nbsp;<strong>Trump fue ampliamente cuestionado sobre sus l\u00edos judiciales, pero dijo que la posibilidad de acabar tras las rejas no le quita el sue\u00f1o<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Ni siquiera pienso en ello&#8221;<\/strong>, dijo Trump cuando Welker le pregunt\u00f3 si por las noches le preocupa el tema de quiz\u00e1 acabar en prisi\u00f3n. &#8220;Estoy construido un poco diferente, supongo, porque he tenido gente que se me acerca y me dice: &#8216;\u00bfC\u00f3mo lo hace, se\u00f1or? \u00bfC\u00f3mo lo hace? Ni siquiera pienso en ello&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Cuando dices, \u00bfpierdo el sue\u00f1o? Yo duermo&#8221;, dijo. &#8220;Duermo. Porque realmente siento que, al final, vamos a ganar&#8221;, asegur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump, quien busca contender nuevamente por la presidencia en 2024, habl\u00f3 sobre lo ocurrido tras las elecciones de noviembre de 2020, cuando asegur\u00f3, sin pruebas, que le robaron la elecci\u00f3n, e intent\u00f3, sin lograrlo, que en Georgia se revirtiera el resultado de los comicios. Luego, el 6 de enero de 2021, cuando el Congreso estaba reunido para certificar el triunfo de Biden, intent\u00f3 que su entonces vicepresidente, Mike Pence, se negara a certificar, algo que Pence rehus\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, Trump habl\u00f3 con una multitud, denunciando el supuesto fraude y pidiendo a la gente defenderlo. Una multitud se dirigi\u00f3 al Capitolio, ingres\u00f3 a la fuerza y puso en riesgo las vidas de los legisladores presentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la entrevista, Trump asumi\u00f3 la responsabilidad de la decisi\u00f3n de intentar revertir su derrota.&nbsp;<strong>&#8220;Fue mi decisi\u00f3n. Pero escuch\u00e9 a algunas personas&#8221;.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuestionado sobre a qui\u00e9nes escuch\u00f3, dijo que &#8220;respet\u00e9 a muchos que dec\u00edan que las elecciones estaban ama\u00f1adas&#8221;. En cambio, no escuch\u00f3 a los asesores que le ped\u00edan reconocer su derrota, y en la entrevista dijo que &#8220;no los respetaba&#8221; y que solo eran republicanos &#8220;de nombre&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Welker le pregunt\u00f3 tambi\u00e9n si hab\u00eda seguido en televisi\u00f3n los eventos del 6 de enero de 2021. &#8220;No te lo voy a decir. Se lo dir\u00e9 a la gente en el momento apropiado&#8221;<\/strong>, respondi\u00f3 el republicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan algunos excolaboradores de Trump, \u00e9ste disfrut\u00f3 viendo lo que ocurr\u00eda en el Capitolio, e incluso repas\u00f3 de nuevo algunas de las cosas que ocurrieron en esa jornada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la periodista le cuestion\u00f3 sobre el por qu\u00e9 guard\u00f3 silencio ante la violencia que se desarrollaba en el Capitolio, siendo \u00e9l presidente, Trump asegur\u00f3 que hizo &#8220;hermosas declaraciones&#8221; ese d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump tambi\u00e9n dijo que le alegraban las recientes declaraciones del presidente ruso, Vladimir Putin, en las que elogiaba al estadounidensepor sugerir que, de ser elegido de nuevo a la Casa Blanca, negociar\u00eda el fin de la guerra de Rusia en Ucrania. Putin dijo el martes que las declaraciones de Trump eran &#8220;buenas&#8221; y tra\u00edan &#8220;felicidad&#8221;. Tambi\u00e9n consider\u00f3 que las acusaciones contra Trump tienen &#8220;motivaciones pol\u00edticas&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Me gusta que haya dicho eso. Porque eso significa que lo que digo es correcto&#8221;, dijo Trump a Welker.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/mundo\/fue-mi-decision-trump-se-responsabiliza-de-acciones-tras-perder-las-elecciones-de-2020\/\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El expresidente estadounidense\u00a0Donald Trump,\u00a0quien enfrenta diversos procesos penales, incluyendo dos por sus intentos de revertir los resultados de las elecciones de 2020, en las que perdi\u00f3 ante\u00a0Joe Biden,\u00a0asegur\u00f3 que fue &#8220;mi decisi\u00f3n&#8221; las acciones emprendidas entonces. Durante una entrevista con la periodista Kristen Welker para el programa Meet the Press, de la cadena NBC, transmitida [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[181],"tags":[5482,230,27309,183],"class_list":["post-121406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-acciones","tag-donald-trump","tag-elecciones-2020","tag-estados-unidos","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/121406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=121406"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/121406\/revisions"}],"predecessor-version":[{"id":121407,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/121406\/revisions\/121407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/4587"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=121406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=121406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=121406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}