{"id":118982,"date":"2023-08-31T08:57:22","date_gmt":"2023-08-31T13:57:22","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=118982"},"modified":"2023-08-31T08:57:23","modified_gmt":"2023-08-31T13:57:23","slug":"inicia-la-feria-internacional-del-libro-infantil-y-juvenil-2023","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/08\/31\/inicia-la-feria-internacional-del-libro-infantil-y-juvenil-2023\/","title":{"rendered":"Inicia la Feria Internacional del Libro Infantil y Juvenil 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue inaugurada la Feria Internacional del Libro Infantil y Juvenil 2023, en las instalaciones del Instituto Veracruzano de la Cultura, en la ciudad de Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la inauguraci\u00f3n la directora del Instituto Veracruzano de Cultura (IVEC), Silvia Alejandre Prado, entreg\u00f3 un reconocimiento a la maestra Sara Elena Benavides de Le\u00f3n por su trayectoria como mediadora de lectura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante esos d\u00edas, el p\u00fablico podr\u00e1 disfrutar de talleres, conversatorios, actividades art\u00edsticas, funciones de cine, cuentacuentos y presentaciones editoriales para toda la familia, adem\u00e1s de una expoventa de libros.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cHabr\u00e1 encuentros virtuales y conversatorios. Tambi\u00e9n funciones de cine, la m\u00fasica y el canto porque son otras formas de comunicarnos. El s\u00e1bado la feria extender\u00e1 su horario para una venta especial con rebajas en los libros\u201d.\u00a0\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Son m\u00e1s de 80 actividades a desarrollarse hasta el 3 de septiembre en el Centro Cultural Exconvento Betlehemita.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cTenemos talleres, presentaciones editoriales y todos los d\u00edas vamos a cerrar con un concierto. Tenemos a las 4,5,6 y 7 de la tarde en el Auditorio presentaciones editoriales con autores como Antonio Malpica, Gabriela Teiron, entre otros de literatura infantil y juvenil. Tambi\u00e9n talleres de danz\u00f3n y salsa\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esta edici\u00f3n de la Feria se sumar\u00e1 a la conmemoraci\u00f3n del A\u00f1o Internacional del Di\u00e1logo como Garant\u00eda de Paz\u00a0\u00a0propuesto por la ONU y ofrecer\u00e1 un nutrido programa de actividades que recordar\u00e1n porque los libros son puertas abiertas al di\u00e1logo emp\u00e1tico y cordial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los pasillos del Exconvento Betlehemita se podr\u00e1n encontrar materiales did\u00e1cticos, libros de uso y los t\u00edtulos de m\u00e1s de 180 fondos editoriales,\u00a0\u00a0representados por 27 expositores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Fue inaugurada la Feria Internacional del Libro Infantil y Juvenil 2023, en las instalaciones del Instituto Veracruzano de la Cultura, en la ciudad de Veracruz. Durante la inauguraci\u00f3n la directora del Instituto Veracruzano de Cultura (IVEC), Silvia Alejandre Prado, entreg\u00f3 un reconocimiento a la maestra Sara Elena Benavides de Le\u00f3n [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":118983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[24821,2835,180],"class_list":["post-118982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-feria-del-libro","tag-ivec","tag-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/118982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=118982"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/118982\/revisions"}],"predecessor-version":[{"id":118984,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/118982\/revisions\/118984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/118983"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=118982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=118982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=118982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}