{"id":114682,"date":"2023-07-23T19:51:00","date_gmt":"2023-07-24T00:51:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=114682"},"modified":"2023-07-23T21:55:01","modified_gmt":"2023-07-24T02:55:01","slug":"ondea-xochitl-galvez-bandera-de-la-paz-con-amlo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/07\/23\/ondea-xochitl-galvez-bandera-de-la-paz-con-amlo\/","title":{"rendered":"Ondea X\u00f3chitl G\u00e1lvez bandera de la paz con AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">X\u00f3chitl G\u00e1lvez arrastra su v\u00e9liz de viaje\u00a0y carga una mochila en sus hombros, llega al vuelo 1036 de Aerom\u00e9xico para tomar su asiento y la recibe un colaborador con las\u00a0<strong>\u00faltimas tendencias y estrategias que se podr\u00edan seguir en esta semana<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sonr\u00ede por la casualidad de que el due\u00f1o de Twitter, Elon Musk, haya lanzado una campa\u00f1a para\u00a0cambiar el logo de sus red social a una \u201cX\u201d. Cruzados los 10 mil pies, trata de dormir, pero su cabeza se lo impide y sigue cruzando ideas con sus colaboradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De momento algunos pasajeros la reconocen, pero esperar\u00e1n a que pasen los 50 minutos de trayecto de la Ciudad de M\u00e9xico a Oaxaca para pedirle una foto&nbsp;<strong>y externarle sus impresiones de su mete\u00f3rica campa\u00f1a en medios y redes sociales.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al aterrizar<strong>\u00a0rechaza que le carguen sus maletas<\/strong>\u00a0y avanza hacia la salida, \u201cpara m\u00ed significa estar mucho en Oaxaca, amo Oaxaca, cuando fui funcionaria vine como 200 veces y dej\u00e9 obras muy importantes para las comunidades\u201d, recuerda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De pronto: \u201c\u00bfme regala una foto?, \u00a1Debe sacarlos el pr\u00f3ximo a\u00f1o!\u201d Le externan mientras se posan para los celulares. Unos pasos m\u00e1s y la misma petici\u00f3n, pero con diferente sentencia: \u201cEstamos contigo, X\u00f3chitl\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al cruzar la salida ya la esperan decenas de mujeres artesanas del estado que&nbsp;<strong>la reciben con huipiles, flores, pulseras, abrazos&nbsp;<\/strong>y el nuevo art\u00edculo de campa\u00f1a: cartones pintados con plum\u00f3n con la leyenda: \u201cX\u00d3CHILT PRESIDENTA\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El avanzar se hace lento, pero la aspirante promete tomarse fotos con todas y cada una de las presentes, se toma unos minutos para ingresar al sanitario y estrenar huipil y con \u00e9l grabar unos videos para que&nbsp;<strong>los turistas nacionales e internacionales compren productos<\/strong>&nbsp;hechos con manos de artesanas oaxaque\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego viene una improvisada, pero\u00a0necesaria limpia a las afueras del aeropuerto oaxaque\u00f1o\u00a0para alejar las \u201cmalas vibras de Palacio Nacional\u201d.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed de dirige al restaurante El Mayordomo donde da una conferencia de prensa en la que le responde a las&nbsp;<em>corcholatas<\/em>, al presidente L\u00f3pez Obrador y deja ver su seguimiento a los temas locales como<strong>&nbsp;la violencia hacia las mujeres y las carencias de servicios.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>X\u00f3chitl G\u00e1lvez asegura que ya super\u00f3 las 150 mil firmas de apoyo&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Afirma que<strong>\u00a0ya super\u00f3 las 150 mil firmas de apoyo<\/strong>\u00a0que pide el comit\u00e9 organizador del Frente Amplio por M\u00e9xico para avanzar a la siguiente ronda, que va encabezando las encuestas del lado opositor y que las\u00a0<em>corcholatas\u00a0<\/em>de Morena \u201cya empezaron con los golpes bajos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00e1lvez lanza un primer mensaje para desmarcarse del ex presidente Vicente Fox, al recalcar que, de ganar la Presidencia, \u201cno volver\u00e1n las pensiones\u201d y que&nbsp;<strong>si los ex mandatarios quieren m\u00e1s dinero \u201cdeben ponerse a trabajar\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insisti\u00f3 en que desde Palacio Nacional hay una campa\u00f1a de violencia pol\u00edtica de g\u00e9nero y buscar\u00e1 que sus abogados ganen ese recurso, tal y como lo gan\u00f3 con su derecho de r\u00e9plica que la trajo al escenario de la competencia nacional.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cVoy a ir a los tribunales, y le voy a ganar, y va a tener que ser inscrito el presidente en la lista de violentadores, porque decir que soy un globo, que me inflan, que soy un t\u00edtere de hombres;&nbsp;<strong>es no saber mi historia y de lo que estoy hecha<\/strong>\u201d, dijo.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tras desayunar con artesanas de Oaxaca que<strong>&nbsp;acusaron al gobernador Salom\u00f3n Jara de eliminarles los apoyos<\/strong>&nbsp;antes y durante la Guelaguetza, G\u00e1lvez se comprometi\u00f3 a buscarles apoyo tal y como lo hizo hace 20 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acusaci\u00f3n tuvo efectos, pues \u201cpor causas ajenas\u201d al sal\u00f3n Herradura, pues<strong>\u00a0integrantes de la comunidad LGBT alargaron su fiesta<\/strong>\u00a0e impidieron que la senadora panista pudiera dar su conferencia en ese punto, por lo que los organizadores improvisaron otro sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Quinta Gloria fue el lugar donde los&nbsp;<em>xochilovers&nbsp;<\/em>se dieron cita, resalta, y much\u00edsimo, la ausencia de camiones, camionetas, la nula entrega de playeras, gorras y&nbsp;<strong>otros souvenirs con las im\u00e1genes de la aspirantes.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed todo es org\u00e1nico: las banderas, son sustituidas por cartones mal cortados; las playeras estampadas, por playeras pintadas con marcador; y las gorras por mo\u00f1os hechos con\u00a0cart\u00f3n simulando una \u201cX\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los asistentes, en su mayor\u00eda adultos y adultos mayores, hicieron escala en la mesa de registro de las firmas del Frente antes de tomar su lugar \u201cap\u00fantame con X\u00f3chitl\u201d, \u201cAh\u00ed, ah\u00ed, ah\u00ed, con X\u00f3chitl\u201d se instru\u00eda a los voluntarios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&#8220;Que Fox se quite del Twitter&#8221;: X\u00f3chitl G\u00e1lvez<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En su ingreso acept\u00f3 otra breve entrevista en la que volvi\u00f3 a echar tierra de por medio con el primer mandatario nacional panista:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cQue (Vicente) Fox se quite del Twitter, por favor.&nbsp;<strong>Ning\u00fan hombre habla por m\u00ed, ni Fox ni nadie.<\/strong>&nbsp;La que dice lo que opina soy yo. Dejen de endosarme declaraci\u00f3n, he condenado ese tuit de Fox donde agrede el origen de Sheinbaum y lo har\u00e9 p\u00fablicamente tr\u00e1tese de quien se trate\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n lament\u00f3 el cambio de sede: \u201cdecirle al gobernador Jara, que fue mi compa\u00f1ero senador, que&nbsp;<strong>yo vengo en son de paz,<\/strong>&nbsp;vengo a dar un mensaje; no es necesario que nos confronte con nadie nosotros no mandamos desalojar a la comunidad LGBT, soy una aliada de esta comunidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diferencia del 90 por ciento lealtad que se necesita en la 4T para ser integrante de gabinete, G\u00e1lvez deline\u00f3 las caracter\u00edsticas que no quiere de ganar las elecciones presidenciales de 2024 \u201clo que s\u00ed les quiero decir es que e<strong>n mi gobierno no habr\u00e1 ni rateros, ni huevones, ni pendejos (sic), lo digo en serio\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 lo org\u00e1nico de su ascenso en la pol\u00edtica, pues sin el dispendio de recursos p\u00fablicos ha robado los reflectores de la pol\u00edtica nacional:&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c\u00bfSaben por qu\u00e9 est\u00e1n enojados? porque nosotros sin espect\u00e1culares, sin bardas les estamos dando la vuelta<strong>, les estamos dando la vuelta con el coraz\u00f3n<\/strong>. Tengo tres semanas que llegu\u00e9, tres semanas y ya est\u00e1 temblando el Presidente como gelatina\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Y onde\u00f3 la bandera de la paz con L\u00f3pez Obrador: \u201cDesde Oaxaca le quiero mandar un mensaje al Presidente, \u00e9l me mand\u00f3 un mensaje de guerra, yo le mand\u00e9 un mensaje de paz.&nbsp;<strong>M\u00e9xico ya no necesita divisi\u00f3n, ni odio,<\/strong>&nbsp;M\u00e9xico necesita unidad. Yo no tengo la culpa, se\u00f1or Presidente, que sus&nbsp;<em>corcholatas&nbsp;<\/em>sean aburridas y no prendan, yo no tengo la culpa, no se enoje conmigo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su mensaje de 45 minutos organiz\u00f3 a los presentes para tomarse foto con cada uno de ellos, acci\u00f3n que dur\u00f3 otros 45 minutos m\u00e1s, \u201cpara darles las gracias por venir aqu\u00ed\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cDe verdad me siento muy feliz en Oaxaca, muy contenta, me gusta mucho, la quiero recorrer en campa\u00f1a, pero&nbsp;<strong>hoy s\u00ed me voy a ir a echar un mezcal, ya me lo merezco<\/strong>\u201d, anunci\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/elecciones\/xochitl-galvez-asegura-haber-alcanzado-las-150-mil-firmas-de-apoyo\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>X\u00f3chitl G\u00e1lvez arrastra su v\u00e9liz de viaje\u00a0y carga una mochila en sus hombros, llega al vuelo 1036 de Aerom\u00e9xico para tomar su asiento y la recibe un colaborador con las\u00a0\u00faltimas tendencias y estrategias que se podr\u00edan seguir en esta semana. Sonr\u00ede por la casualidad de que el due\u00f1o de Twitter, Elon Musk, haya lanzado una [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":85413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[158],"tags":[188,3679,162,21609],"class_list":["post-114682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-amlo","tag-firmas","tag-portada","tag-xochitl-galvez","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=114682"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114682\/revisions"}],"predecessor-version":[{"id":114683,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114682\/revisions\/114683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/85413"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=114682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=114682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=114682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}