{"id":114672,"date":"2023-07-23T15:58:35","date_gmt":"2023-07-23T20:58:35","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=114672"},"modified":"2023-07-23T15:58:36","modified_gmt":"2023-07-23T20:58:36","slug":"el-agua-llega-sucia-a-las-colonias-de-veracruz-acusan-usuarios","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/07\/23\/el-agua-llega-sucia-a-las-colonias-de-veracruz-acusan-usuarios\/","title":{"rendered":"El agua llega sucia a las colonias de Veracruz, acusan usuarios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El agua contin\u00faa llegando a sucia a algunas colonias y fraccionamientos de la ciudad de Veracruz. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La se\u00f1ora Dolores Toral dijo que es el caso del Infonavit Buenavista, en donde tiene que ocupar filtros para que le salga agua limpia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mencion\u00f3 que cuando abre la llave el l\u00edquido es caf\u00e9 y no puede lavar la ropa o llevar a cabo labores del hogar con dicha calidad del elemento.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPara lavar tiene uno que ponerle un trapo para que filtre\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se quej\u00f3 de cobros excesivos, ya que en su caso, enfrentaba un adeudo de 6 mil 800 pesos y estableci\u00f3 un convenio con la empresa para pagarlo a 6 meses. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de haber solventado cinco meses le dijeron que deb\u00eda lo mismo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tal motivo dej\u00f3 de pagar y ahora debe 23 mil pesos por consumo de agua.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEran 6 mil 800 pesos, me lo rebajaron y ten\u00eda que pagar 5 mil 200 y hab\u00eda pagado cinco meses porque se supone que era dividido en seis meses lo que iba a pagar. Me dijeron que como eran m\u00e1s de 6 mil lo pagara en seis meses pero a los seis meses me dec\u00edan que deb\u00eda 5 mil y tantos pero ya son 23 mil. Si no es banco para que cobre intereses\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para evitar que le cortaran el servicio se ampar\u00f3, sin embargo, recrimin\u00f3 que el Grupo Metropolitano del Agua no env\u00ede l\u00edquido de calidad a los hogares, no invierta en la infraestructura que utiliza para la distribuci\u00f3n del agua y que cobre altas tarifas a los usuarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias El agua contin\u00faa llegando a sucia a algunas colonias y fraccionamientos de la ciudad de Veracruz. La se\u00f1ora Dolores Toral dijo que es el caso del Infonavit Buenavista, en donde tiene que ocupar filtros para que le salga agua limpia. Mencion\u00f3 que cuando abre la llave el l\u00edquido es caf\u00e9 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":100344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[594,1167,26427,3237,180],"class_list":["post-114672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-agua","tag-colonias","tag-sucia","tag-usuarios","tag-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=114672"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114672\/revisions"}],"predecessor-version":[{"id":114673,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/114672\/revisions\/114673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/100344"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=114672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=114672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=114672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}