{"id":113072,"date":"2023-07-09T14:37:06","date_gmt":"2023-07-09T19:37:06","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=113072"},"modified":"2023-07-09T14:37:06","modified_gmt":"2023-07-09T19:37:06","slug":"xochitl-la-candidata-populista-para-combatir-al-populismo-de-amlo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/07\/09\/xochitl-la-candidata-populista-para-combatir-al-populismo-de-amlo\/","title":{"rendered":"X\u00f3chitl, la candidata populista para combatir al populismo de AMLO"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Por Mois\u00e9s Hern\u00e1ndez Yoldi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La irrupci\u00f3n de X\u00f3chitl G\u00e1lvez en la carrera por la presidencia de la republica, ha venido a darle una fuerte inyecci\u00f3n de entusiasmo a la oposici\u00f3n, que hasta antes de su aparici\u00f3n, parec\u00eda tener m\u00ednimas posibilidades de competirle a la maquinaria pol\u00edtica electoral de Morena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado en el Estado de M\u00e9xico, dej\u00f3 mal parada a la alianza opositora integrada por PRI-PAN-PRD, el entusiasmo entre los opositores al r\u00e9gimen de la llamada 4T, se sosten\u00eda en la fe y en la esperanza de que \u201calgo\u201d podr\u00eda cambiar el rumbo de las cosas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese \u201calgo\u201d lleg\u00f3 con la aparici\u00f3n de X\u00f3chitl G\u00e1lvez, una mujer de 60 a\u00f1os, nacida en el pueblo de Tepatepec, en el coraz\u00f3n Del Valle del Mezquital en el Estado de Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ingeniera de profesi\u00f3n y activista social por vocaci\u00f3n, G\u00e1lvez tiene una historia de superaci\u00f3n digna de admirar, logr\u00f3 salir de la pobreza en base a esfuerzo, persistencia y valor, se revel\u00f3 a su destino y alcanz\u00f3 el \u00e9xito profesional y econ\u00f3mico al crear una empresa llamada High Tec Services, especializada en el desarrollo de proyectos de alta tecnolog\u00eda dirigidos al dise\u00f1o de edificios inteligentes, automatizados y sustentables. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de su carrera empresarial, ha sido objeto de m\u00faltiples premios y reconocimientos por lograr equilibrio entre el \u00e9xito econ\u00f3mico profesional y su labor social y compromiso con la sustentabilidad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los reconocimientos m\u00e1s destacados se encuentra el haber seleccionada en 1999 entre los 100 l\u00edderes globales del futuro del mundo en el World Economic Forum en Davos, Suiza y en el a\u00f1o 2000 la revista Business Week la incluy\u00f3 en la lista de los \u201c25 Latin American\u2019s New Business Elite\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00e1rea social, creo la fundaci\u00f3n Porvenir, que se dedica a combatir la pobreza, desnutrici\u00f3n y a fomentar el desarrollo econ\u00f3mico en zonas y comunidades ind\u00edgenas en los estados de Chiapas, Hidalgo, Oaxaca y Puebla. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su irrupci\u00f3n en la pol\u00edtica se dio luego de ser reclutada en el a\u00f1o 2000 por el staff de caza talentos que ayud\u00f3 a conformar el gabinete de Vicente Fox, quien la design\u00f3 como directora del Instituto Nacional de los Pueblos Ind\u00edgenas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2010, fue candidata a la gubernatura de Hidalgo por la coalici\u00f3n integrada por PAN-PRD-MC-PT. Del 2015 al 2016 fue jefa de la Delegaci\u00f3n Miguel Hidalgo en la CDMX. Desde el 2018 es senadora de la Rep\u00fablica por el PAN. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda el curr\u00edculum de X\u00f3chitl G\u00e1lvez es admirable, por ello no deber\u00eda de sorprender que su postulaci\u00f3n haya despertado tanto entusiasmo entre los opositores al r\u00e9gimen del presidente L\u00f3pez Obrador. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">X\u00f3chitl G\u00e1lvez ser\u00eda la opci\u00f3n \u201cpopulista\u201d de la oposici\u00f3n, ante el \u201cpopulismo\u201d de AMLO, que paradojas, pero como dicen en pol\u00edtica, circunstancia manda, y la circunstancia hoy es que a\u00fan persiste entre la poblaci\u00f3n y los votantes, un alto rechazo en contra de todo aquello y aquellos que se asocien con la aristocracia pol\u00edtica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo esa l\u00f3gica, ni Santiago Creel, ni Enrique De la Madrid tienen cabida en una elecci\u00f3n donde la cercan\u00eda con la gente ser\u00e1 fundamental y tal vez decisiva. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Factores como el origen \u00e9tnico, los rasgos raciales, el color de piel, la idiosincrasia, la forma de hablar y hasta de vestir, son elementos que juegan en el hemisferio de las emociones, y actualmente la sociedad est\u00e1 cargada de sentimientos que influyen en sus decisiones. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este gobierno se ha encargado de exacerbar las emociones entre la sociedad, sentimientos a\u00f1ejos han aflorado y otros m\u00e1s se han acumulado a los largo de estas \u00faltimas d\u00e9cadas en contra las \u00e9lites; el gobierno de AMLO es un gobierno de emociones, L\u00f3pez Obrador sabe mover conciencias y voluntades, lo hace a trav\u00e9s de su discurso, aplicando t\u00e9cnicas narrativas que exaltan el nacionalismo, la soberan\u00eda y el rechazo hacia la burgues\u00eda y todo aquello que se asocie al modelo neoliberal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese escenario, la oposici\u00f3n ha optado por intentar con una candidatura populista, muy similar a lo que propone el \u201clopezobradorismo\u201d, por ello, la figura de X\u00f3chitl hace tanto sentido y se convierte en un reto para la estrategia del presidente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Competir contra un pol\u00edtico de carrera como Enrique De la Madrid, con todo lo que representa: blanco, hijo de un ex presidente y ademas priista, supone una competencia a modo en favor de L\u00f3pez Obrador y estrategia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfrentar a Santiago Creel es otro out cantado, un panista de la vieja guardia que ha distinguido por su personalidad fr\u00eda y gris. Un pol\u00edtico que ha subsistido en la burocracia pol\u00edtica, acomod\u00e1ndose en los gobiernos de Fox, Calderon y Pe\u00f1a Nieto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo de X\u00f3chitl es un as bajo la manga que pocos pod\u00edan predecir, es jugar por la izquierda contra la izquierda; su postulaci\u00f3n no es una ocurrencia, es el resultado de un profundo an\u00e1lisis antropol\u00f3gico, social y pol\u00edtico de un gabinete de especialistas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes hoy postulan a X\u00f3chitl G\u00e1lvez, son los mismos que impulsaron a Lilly T\u00e9llez, y que al medir el impacto de una candidata que apostaba por entusiasmar al segmento conservador de derecha, decidieron hacer switch con la opci\u00f3n de \u201cizquierda\u201d dentro del proyecto opositor que busca gravarle a la 4T. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El grupo de expertos que trabajan en el laboratorio pol\u00edtico que analiza, mido, traza y propone, est\u00e1 financiado por un grupo de empresarios de elite, la cara visible de ese grupo es Claudio X Gonz\u00e1lez, es \u00e9l quien se ha encargado de sentar en la misma mesa al PRI, PAN y lo que queda del PRD, y que hace intentos desesperados por convencer a Dante Delgado y su Movimiento Ciudadano, para que se sume a la alianza de oposici\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 hace tan desafiante la virtual candidatura de X\u00f3chitl G\u00e1lvez para el proyecto de continuidad de Lopez Obrador? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Origen: ind\u00edgena<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Personalidad: alegre, feminista y luchona<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Vestimenta: usa ropa aut\u00f3ctona (huipil)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Su forma de hablar: habla como el pueblo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Historia de superaci\u00f3n: vendi\u00f3 tamales y gelatinas de ni\u00f1a y se convirti\u00f3 en una empresaria exitosa <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">X\u00f3chitl es un compendio de atributos que el pueblo mexicano valora y admira, es la s\u00edntesis del verdadero \u201cpueblo bueno\u201d del que tanto habla el presidente L\u00f3pez Obrador. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso es en la forma, en el fondo hay a\u00fan m\u00e1s criptonita para los candidatos de la 4T, en su discurso X\u00f3chitl apoya los programas sociales que tan rebtables resultan en t\u00e9rminos pol\u00edticos electorales, asegura que no solo les dar\u00e1 continuidad, sino que los ampliar\u00e1 y mejorar\u00e1, ese discurso no solo es contrario a los fundamentos del neoliberalismo econ\u00f3mico, tambi\u00e9n rompe todo esquema para atacarla en ese frente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En contrasentido a los principios del panismo tradicional, ligado a los valores de la iglesia cat\u00f3lica, X\u00f3chitl se declara a favor de la legalizaci\u00f3n de las drogas, confes\u00f3 haber consumido peyote y hayahuasca; est\u00e1 a favor de la legalizaci\u00f3n del aborto y en favor de los matrimonios homosexuales y la adopci\u00f3n homoparental; tal c\u00famulo de contradicciones ideol\u00f3gicas, solo son posibles ante la urgente necesidad de la posici\u00f3n de presentar un candidato, en este caso candidata, que pueda competirle a Lopez Obrador y su candidato. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los candidatos del presidente, hablar\u00e9 en otro post.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Mois\u00e9s Hern\u00e1ndez Yoldi La irrupci\u00f3n de X\u00f3chitl G\u00e1lvez en la carrera por la presidencia de la republica, ha venido a darle una fuerte inyecci\u00f3n de entusiasmo a la oposici\u00f3n, que hasta antes de su aparici\u00f3n, parec\u00eda tener m\u00ednimas posibilidades de competirle a la maquinaria pol\u00edtica electoral de Morena. El resultado en el Estado de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":113073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-113072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/113072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=113072"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/113072\/revisions"}],"predecessor-version":[{"id":113074,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/113072\/revisions\/113074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/113073"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=113072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=113072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=113072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}