{"id":11250,"date":"2021-04-18T14:24:58","date_gmt":"2021-04-18T19:24:58","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=11250"},"modified":"2021-04-18T14:25:39","modified_gmt":"2021-04-18T19:25:39","slug":"pide-obispo-no-saltarse-fila-recibir-vacuna-coronavirus","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/04\/18\/pide-obispo-no-saltarse-fila-recibir-vacuna-coronavirus\/","title":{"rendered":"Pide obispo no saltarse la fila para recibir la vacuna contra el coronavirus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El obispo de Veracruz, Carlos Brise\u00f1o Arch, exhort\u00f3 a los veracruzanos a ser pacientes y esperar su turno para recibir la vacuna contra el coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 positivo\u00a0 que las dosis se aplicar\u00e1n primero a trabajadores del sector salud, adultos mayores y posteriormente se pretenda hacerlo con los maestros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Admiti\u00f3 que a veces falta ser civilizado pues se trata de aprovecharse de las condiciones y abusar de otros, pero si existe un orden debe acatarse ya que todos tendr\u00e1n su turno para recibir la vacuna.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cA veces queremos agandallar pero a todos nos va a tocar tarde o temprano. No pensemos que a unos si y a tris no, hay que darle tiempo al tiempo. Yo creo que para noviembre gran parte de la poblaci\u00f3n estar\u00e1 vacunada\u201d.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Vio con esperanza la jornada de vacunaci\u00f3n ya que ayudar\u00e1 a prevenir un padecimiento fuerte o la muerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exhort\u00f3 a mantener las precauciones sanitarias necesarias, pues el restablecimiento de las condiciones tardar\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Admiti\u00f3 que las limitaciones seguir\u00e1n, sin embargo, pueden aminorarse paulatinamente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cSabemos que es una cosa buena, como todas las cosas tiene su riesgo pero no atenta contra la vida, va a protegernos de una enfermedad grave o de morir. La gente se est\u00e1 vacunando y poco a poco se ir\u00e1 extendiendo. Todo este a\u00f1o seguir\u00e1 el esquema de vacunaci\u00f3n y de seguir cuid\u00e1ndonos\u201d.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado confirmo que en la Di\u00f3cesis se dieron dos nuevos casos de coronavirus pero no graves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que la mayor\u00eda de los sacerdotes de la tercera edad se vacunaron para cuidarse y cuidar a los dem\u00e1s ante posibles contagios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias El obispo de Veracruz, Carlos Brise\u00f1o Arch, exhort\u00f3 a los veracruzanos a ser pacientes y esperar su turno para recibir la vacuna contra el coronavirus. Consider\u00f3 positivo\u00a0 que las dosis se aplicar\u00e1n primero a trabajadores del sector salud, adultos mayores y posteriormente se pretenda hacerlo con los maestros. Admiti\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":11251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[156],"tags":[1833,359,3081,809],"class_list":["post-11250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-carlos-briseno-arch","tag-coronavirus","tag-obispo-de-veracruz","tag-vacunacion","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/11250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11250"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/11250\/revisions"}],"predecessor-version":[{"id":11252,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/11250\/revisions\/11252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/11251"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}