{"id":109365,"date":"2023-06-06T14:35:55","date_gmt":"2023-06-06T19:35:55","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=109365"},"modified":"2023-06-06T14:35:55","modified_gmt":"2023-06-06T19:35:55","slug":"realizan-la-jornada-de-cirugias-de-labio-y-paladar-hendido","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/06\/06\/realizan-la-jornada-de-cirugias-de-labio-y-paladar-hendido\/","title":{"rendered":"Realizan la jornada de cirug\u00edas de labio y paladar hendido"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde Juan Manuel de Un\u00e1nue encabez\u00f3 la jornada de cirug\u00edas de labio y paladar hendido que se llevar\u00e1n a cabo en el Hospital Covadonga de Boca del R\u00edo, gracias al apoyo y colaboraci\u00f3n de la Fundaci\u00f3n Austin Smiles, la fundaci\u00f3n S\u00e1nchez Ancira y al Distrito Rotario 4185.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se realizar\u00e1n al menos 60 cirug\u00edas a partir de este lunes 5 de junio, los beneficiados no solo ser\u00e1n ni\u00f1as y ni\u00f1os boque\u00f1os, sino que tambi\u00e9n se brindar\u00e1 atenci\u00f3n a menores de municipios aleda\u00f1os con la finalidad de mejorar su calidad de vida.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;<em>Estoy convencido que la sinergia entre dependencias gubernamentales y las organizaciones civiles seguir\u00e1n llevando m\u00e1s sonrisas a muchos hogares veracruzanos. Es un gusto para m\u00ed que este d\u00eda inicie este gran programa, gracias a las manos generosas del personal m\u00e9dico de la Fundaci\u00f3n Austin Smiles, as\u00ed como de la enorme solidaridad de la familia Sanchez Ancira<\/em>&#8220;, dijo el alcalde Juan Manuel Un\u00e1nue.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde afirm\u00f3 que su compromiso es vincular su administraci\u00f3n municipal con m\u00e1s sectores y se pueda construir un mejor espacio para mejorar la vida de muchas familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el presidente del Club Rotario Costa de Oro, Ramiro Ram\u00edrez, inform\u00f3 que la Fundaci\u00f3n Austin Smiles envi\u00f3 desde Texas a 31 voluntarios, entre cirujanos, anestesistas y dem\u00e1s m\u00e9dicos especialistas, as\u00ed como personal de apoyo para realizar las cirug\u00edas en Boca del R\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta jornada es un conjunto de esfuerzos para lograr que cada operaci\u00f3n, as\u00ed como el transporte, alimentos y estancia, fueran gratuitos para los beneficiados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este evento se cont\u00f3 tambi\u00e9n con la presencia de Reene Handson, representante de la fundaci\u00f3n Austin Smiles; Marcelo Andrade Rodr\u00edguez, director del Hospital Covadonga; Fernanda S\u00e1nchez Sainz, representante de la Fundaci\u00f3n S\u00e1nchez Ancira; Ramiro Rodr\u00edguez Navarrete, presidente del Club Rotario Boca del R\u00edo Costa de Oro, e Ileana Huesca, directora del DIF municipal de Veracruz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias El alcalde Juan Manuel de Un\u00e1nue encabez\u00f3 la jornada de cirug\u00edas de labio y paladar hendido que se llevar\u00e1n a cabo en el Hospital Covadonga de Boca del R\u00edo, gracias al apoyo y colaboraci\u00f3n de la Fundaci\u00f3n Austin Smiles, la fundaci\u00f3n S\u00e1nchez Ancira y al Distrito Rotario 4185. Se realizar\u00e1n [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":109366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[25618,25619],"class_list":["post-109365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-jornada-de-cirugias","tag-labio-y-paladar-hendido","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=109365"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109365\/revisions"}],"predecessor-version":[{"id":109367,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109365\/revisions\/109367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/109366"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=109365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=109365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=109365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}