{"id":109089,"date":"2023-06-04T12:11:45","date_gmt":"2023-06-04T17:11:45","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=109089"},"modified":"2023-06-04T12:11:46","modified_gmt":"2023-06-04T17:11:46","slug":"emiten-advertencia-por-evolucion-de-virus-h5n1-de-gripe-aviar","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/06\/04\/emiten-advertencia-por-evolucion-de-virus-h5n1-de-gripe-aviar\/","title":{"rendered":"Emiten advertencia por evoluci\u00f3n de virus H5N1 de gripe aviar"},"content":{"rendered":"\n<p>El\u00a0virus H5N1, que origin\u00f3 una\u00a0ola r\u00e9cord de gripe aviar en el mundo, evoluciona r\u00e1pidamente, advierten expertos, cuando aumentan los llamados para que los pa\u00edses vacunen a sus aves.<\/p>\n\n\n\n<p>Si el riesgo para el humano sigue siendo d\u00e9bil, el n\u00famero creciente de casos entre los mam\u00edferos es considerado preocupante<strong>,<\/strong>&nbsp;seg\u00fan especialistas interrogados por la AFP.<\/p>\n\n\n\n<p>Desde su aparici\u00f3n, en 1996, el virus de la gripe aviar H5N1 provocaba contagios de temporada.<\/p>\n\n\n\n<p>Pero &#8220;algo sucedi\u00f3&#8221; a mediados de 2021, pues el\u00a0virus se volvi\u00f3 m\u00e1s infeccioso,\u00a0seg\u00fan Richard Webby, vir\u00f3logo y director del centro de investigaci\u00f3n sobre las patolog\u00edas aviarias de la\u00a0Organizaci\u00f3n Mundial de la Salud\u00a0(OMS).<\/p>\n\n\n\n<p>Desde entonces, las epizootias se volvieron anuales, se extendieron a nuevas zonas, lo que caus\u00f3 muertes masivas de p\u00e1jaros salvajes y la eliminaci\u00f3n de decenas de millones de aves. Para Webby, es la mayor epizootia de gripe aviar jam\u00e1s conocida.<\/p>\n\n\n\n<p>Richard Webby dirigi\u00f3 las investigaciones, publicadas esta semana en la revista Nature Communications, que muestra que el virus evolucion\u00f3 r\u00e1pidamente propag\u00e1ndose de Europa hacia Am\u00e9rica del Norte.<\/p>\n\n\n\n<p>Los investigadores tambi\u00e9n infectaron un hur\u00f3n con una de las nuevas cepas de la gripe aviar. Hallaron una cantidad\u00a0&#8220;enorme&#8221; e inesperada de virus en su cerebro, lo que muestra una enfermedad m\u00e1s grave que con las cepas anteriores, dijo a la AFP.<\/p>\n\n\n\n<p>Al mismo tiempo que se\u00f1ala un riesgo aun d\u00e9bil para el hombre, Webby observ\u00f3 que &#8220;ese virus no es est\u00e1tico sino que evoluciona&#8221;, lo que &#8220;aumenta el riesgo de que, inclusive por azar&#8221;, el virus pueda &#8220;adquirir trazos gen\u00e9ticos que le permitan convertirse en virus humano&#8221;.<\/p>\n\n\n\n<p>Son pocos los casos de humanos que contrajeron el virus, a veces mortal, generalmente tras un contacto estrecho con p\u00e1jaros infectados.<\/p>\n\n\n\n<p>Pero la detecci\u00f3n de la enfermedad en un n\u00famero creciente de mam\u00edferos, incluidas nuevas especies, es &#8220;un signo verdaderamente preocupante&#8221;, indic\u00f3 Richard Webby.<\/p>\n\n\n\n<p>La semana pasada, Chile anunci\u00f3 que cerca de 9 mil leones de mar, ping\u00fcinos, nutrias, marsopas y delfines murieron de gripe aviar\u00a0en la costa norte desde inicios de 2023. La mayor\u00eda habr\u00edan contra\u00eddo el virus al comer p\u00e1jaros infectados.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Las recientes transmisiones a mam\u00edferos deben ser vigiladas de cerca&#8221;, advirti\u00f3 en febrero el jefe de la Organizaci\u00f3n Mundial de la Salud, Tedros Adhanom Ghebreyesus.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Preocupa evoluci\u00f3n del virus<\/h2>\n\n\n\n<p>Sin embargo, no hay &#8220;pruebas claras de que ese virus permanezca f\u00e1cilmente en los mam\u00edferos&#8221;, seg\u00fan Ian Brown, responsable de la virolog\u00eda en la Agencia brit\u00e1nica de salud animal y vegetal.<\/p>\n\n\n\n<p>Y aunque el virus sigue evolucionando para ser &#8220;m\u00e1s eficaz en las aves&#8221;, sigue siendo &#8220;inadecuado para los humanos&#8221;, indic\u00f3 a la AFP.<\/p>\n\n\n\n<p>Los virus de tipo aviar se ligan con receptores diferentes en la c\u00e9lula anfitriona a diferencia de los virus humanos, precis\u00f3 Richard Webby. Precis\u00f3 que se requerir\u00edan &#8220;dos o tres mutaciones menores en una prote\u00edna de los virus&#8221; para que se vuelvan adaptables a los humanos.<\/p>\n\n\n\n<p>Uno de los medios para disminuir el n\u00famero de casos de gripe aviar y de reducir el riesgo para los humanos ser\u00eda la vacunaci\u00f3n de las aves, subray\u00f3 Richard Webby.<\/p>\n\n\n\n<p>Algunos pa\u00edses, entre ellos China, Egipto o Vietnam, ya organizaron campa\u00f1as de vacunaci\u00f3n. Pero muchos otros son reticentes por las posibles restricciones de importaciones y temores de que los p\u00e1jaros infectados pasen a trav\u00e9s de los controles.<\/p>\n\n\n\n<p>En abril, Estados Unidos comenz\u00f3 a hacer pruebas de vacunas para una utilizaci\u00f3n potencial en los p\u00e1jaros. Francia indic\u00f3 recientemente que espera comenzar a vacunar aves desde el oto\u00f1o.<\/p>\n\n\n\n<p>La vacuna de aves no es &#8220;una soluci\u00f3n milagrosa pues el virus cambia constantemente&#8221;, seg\u00fan Christine Middlemiss, veterinaria en jefe del Reino Unido.<\/p>\n\n\n\n<p>Fuente:<a href=\"https:\/\/www.eluniversal.com.mx\/mundo\/preocupa-a-expertos-evolucion-de-virus-de-gripe-aviar-y-emiten-advertencia\/\"> El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0virus H5N1, que origin\u00f3 una\u00a0ola r\u00e9cord de gripe aviar en el mundo, evoluciona r\u00e1pidamente, advierten expertos, cuando aumentan los llamados para que los pa\u00edses vacunen a sus aves. Si el riesgo para el humano sigue siendo d\u00e9bil, el n\u00famero creciente de casos entre los mam\u00edferos es considerado preocupante,&nbsp;seg\u00fan especialistas interrogados por la AFP. Desde su [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":109090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[181],"tags":[1573,25584],"class_list":["post-109089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-gripe-aviar","tag-virus-h5n1","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=109089"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109089\/revisions"}],"predecessor-version":[{"id":109091,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/109089\/revisions\/109091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/109090"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=109089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=109089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=109089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}