{"id":108182,"date":"2023-05-27T15:53:47","date_gmt":"2023-05-27T20:53:47","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=108182"},"modified":"2023-05-27T15:53:48","modified_gmt":"2023-05-27T20:53:48","slug":"recibe-visitantes-el-buque-escuela-simon-bolivar-de-venezuela","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/05\/27\/recibe-visitantes-el-buque-escuela-simon-bolivar-de-venezuela\/","title":{"rendered":"Recibe visitantes el buque escuela Sim\u00f3n Bol\u00edvar, de Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los habitantes de Veracruz como los turistas se congregaron en el muelle de la T con el fin de visitar y explorar el buque escuela Sim\u00f3n Bol\u00edvar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los representantes de la embarcaci\u00f3n destacaron que la misi\u00f3n del buque consiste en entrenar a los futuros oficiales de la fuerza armada de Venezuela. Durante la visita, los visitantes podr\u00e1n recorrer las cubiertas externas y entablar un di\u00e1logo con los cadetes para conocer m\u00e1s sobre la parte acad\u00e9mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cadetes compartir\u00e1n sus experiencias durante el recorrido y tambi\u00e9n habr\u00e1 oportunidad de intercambiar aspectos culturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La se\u00f1ora Mar\u00eda Luisa Aguayo, una visitante proveniente de Puebla, consider\u00f3 que la llegada de este buque estrechar\u00e1 los lazos entre Venezuela y M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el buque viajan j\u00f3venes de quinto semestre que cursan uno de los ocho semestres de la carrera militar, permiti\u00e9ndoles adquirir conocimientos pr\u00e1cticos. Solo durante la ma\u00f1ana del s\u00e1bado, se registr\u00f3 la visita de mil quinientas personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 30 de mayo, el buque zarpar\u00e1 de Veracruz con rumbo a Yucat\u00e1n, y posteriormente continuar\u00e1 su traves\u00eda hacia Cartagena, Colombia, donde permanecer\u00e1 del 25 al 29 de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante destacar que esta no es la primera vez que el buque escuela Sim\u00f3n Bol\u00edvar visita el Puerto de Veracruz. En julio de 2019, durante su XXXI crucero de instrucci\u00f3n, tambi\u00e9n tuvo la oportunidad de atracar en estas tierras. Por tanto, esta pr\u00f3xima visita marca la novena ocasi\u00f3n en la que la embarcaci\u00f3n arriba a esta regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Los habitantes de Veracruz como los turistas se congregaron en el muelle de la T con el fin de visitar y explorar el buque escuela Sim\u00f3n Bol\u00edvar. Los representantes de la embarcaci\u00f3n destacaron que la misi\u00f3n del buque consiste en entrenar a los futuros oficiales de la fuerza armada de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":107998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[2627,25393,7909,1540,10197],"class_list":["post-108182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-buque","tag-buque-escuela-simon-bolivar","tag-recibe","tag-venezuela","tag-visitantes","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=108182"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108182\/revisions"}],"predecessor-version":[{"id":108183,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108182\/revisions\/108183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/107998"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=108182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=108182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=108182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}