{"id":108137,"date":"2023-05-27T12:55:38","date_gmt":"2023-05-27T17:55:38","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=108137"},"modified":"2023-05-27T12:55:40","modified_gmt":"2023-05-27T17:55:40","slug":"detienen-a-presunto-autor-intelectual-del-asesinato-de-periodista-en-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/05\/27\/detienen-a-presunto-autor-intelectual-del-asesinato-de-periodista-en-veracruz\/","title":{"rendered":"Detienen a presunto autor intelectual del asesinato de periodista en Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador del estado de Veracruz,\u00a0<strong>Cuitlah\u00faac Garc\u00eda Jim\u00e9nez,<\/strong>\u00a0confirm\u00f3 la detenci\u00f3n de Alfredo Ernesto en Tampico,\u00a0Tamaulipas, presunto autor intelectual del asesinato de la periodista\u00a0<strong>Mar\u00eda Elena Ferral Hern\u00e1ndez<\/strong>, corresponsal del Diario de Xalapa que fue privada de la vida el 30 de marzo de 2020 en el municipio de Papantla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bEn entrevista en su visita a Coatzacoalcos,&nbsp;<strong>Garc\u00eda Jim\u00e9nez<\/strong>&nbsp;indic\u00f3 que con esta detenci\u00f3n suman 9 personas detenidas; tres de ellas&nbsp;<strong>ya fueron sentenciadas<\/strong>&nbsp;con 30 a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Est\u00e1 detenci\u00f3n se suma a otras 8 que hemos realizado por este caso donde tres ya fueron sentenciados, y nosotros&nbsp;<strong>agradecemos a al CONASE por su colaboraci\u00f3n<\/strong>&nbsp;y coordinaci\u00f3n, porque viene a dar justicia a un hecho muy relevante&#8221;, indic\u00f3&nbsp;<strong>Garc\u00eda Jim\u00e9nez<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ernesto, quien fue identificado como empresario, es una persona clave en el asesinato de&nbsp;<strong>Mar\u00eda Elena Ferral<\/strong>. De acuerdo con investigaciones del caso, \u00e9l era due\u00f1o de la tortiller\u00eda &#8220;Lucy&#8221;, un negocio que era una fachada ya que en realidad serv\u00eda para&nbsp;<strong>distribuir droga en el municipio de Papantla<\/strong>&nbsp;y alrededores, en la regi\u00f3n norte de Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se le acusa de tener relaci\u00f3n con una moto marca Cargo que fue&nbsp;<strong>empleada para asesinar a Ferral<\/strong>&nbsp;en la entrada de una notar\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese veh\u00edculo, confirmaron fuentes ministeriales, estaba a nombre de\u00a0<strong>Luc\u00eda P\u00e9rez Cano<\/strong>, esposa del detenido, quien adem\u00e1s era hermana de Jos\u00e9 P\u00e9rez Cano,\u00a0<strong>exdirigente municipal del Partido Verde<\/strong>\u00a0en el municipio de Guti\u00e9rrez Zamora, asesinado el 5 de marzo de 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/estados\/detienen-a-sospechoso-por-asesinato-de-periodista-en-veracruz\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/estados\/detienen-a-sospechoso-por-asesinato-de-periodista-en-veracruz\">Milenio<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador del estado de Veracruz,\u00a0Cuitlah\u00faac Garc\u00eda Jim\u00e9nez,\u00a0confirm\u00f3 la detenci\u00f3n de Alfredo Ernesto en Tampico,\u00a0Tamaulipas, presunto autor intelectual del asesinato de la periodista\u00a0Mar\u00eda Elena Ferral Hern\u00e1ndez, corresponsal del Diario de Xalapa que fue privada de la vida el 30 de marzo de 2020 en el municipio de Papantla. \u200bEn entrevista en su visita a Coatzacoalcos,&nbsp;Garc\u00eda [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":7348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[1431,7612,5841,23309,1106,2120],"class_list":["post-108137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-asesinato","tag-autor","tag-detienen","tag-intelectual","tag-periodista","tag-presunto","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=108137"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108137\/revisions"}],"predecessor-version":[{"id":108141,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/108137\/revisions\/108141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/7348"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=108137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=108137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=108137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}