{"id":10503,"date":"2021-04-10T10:19:00","date_gmt":"2021-04-10T15:19:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=10503"},"modified":"2021-04-10T10:19:21","modified_gmt":"2021-04-10T15:19:21","slug":"hoy-ultimo-dia-recojas-credencial-elector","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/04\/10\/hoy-ultimo-dia-recojas-credencial-elector\/","title":{"rendered":"Hoy es el \u00faltimo d\u00eda para que recojas tu credencial de elector"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy 10 de abril vence el plazo para que las personas que tramitaron la credencial de elector la recojan, inform\u00f3 Nelson Hern\u00e1ndez Rojas, vocal ejecutivo de la Junta Distrital n\u00famero 12 del Instituto Nacional Electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si no lo hacen a m\u00e1s tardar hoy, la mica quedar\u00e1 bajo resguardo del INE y ser\u00e1 entregada despu\u00e9s del 6 de junio, d\u00eda de la elecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes la solicitaron pudo ser por inscripci\u00f3n al padr\u00f3n, correcci\u00f3n de datos, reposici\u00f3n por vencimiento, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s el 25 de mayo vence el plazo para que la ciudadan\u00eda pueda obtener una reposici\u00f3n de credencial para votar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, sin cambio de datos personales.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cSi se le extrav\u00eda, se la roban o se deteriora podr\u00e1n acercarse a los m\u00f3dulos a solicitar una reimpresi\u00f3n. No modifica la foto ni dato alguno, es la misma credencial que extrav\u00edo o se le deterior\u00f3\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Estas credenciales podr\u00e1n recogerse a m\u00e1s tardar el 4 de junio, pues no modifica el listado nominal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 30 de mayo tambi\u00e9n es la fecha l\u00edmite para que los partidos pol\u00edticos presenten observaciones a la lista nominal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que concluyan los procesos de validaci\u00f3n, el Consejo General aprobar\u00e1 de forma definitiva dicho listado para imprimir los datos para las mesas directivas de casilla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias Hoy 10 de abril vence el plazo para que las personas que tramitaron la credencial de elector la recojan, inform\u00f3 Nelson Hern\u00e1ndez Rojas, vocal ejecutivo de la Junta Distrital n\u00famero 12 del Instituto Nacional Electoral. Si no lo hacen a m\u00e1s tardar hoy, la mica quedar\u00e1 bajo resguardo del INE [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":10504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[1178,443,445,162],"class_list":["post-10503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-credencial-de-elector","tag-ine","tag-instituto-nacional-electoral","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/10503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10503"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/10503\/revisions"}],"predecessor-version":[{"id":10505,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/10503\/revisions\/10505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/10504"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}