{"id":104935,"date":"2023-04-29T12:22:56","date_gmt":"2023-04-29T17:22:56","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=104935"},"modified":"2023-04-29T12:22:57","modified_gmt":"2023-04-29T17:22:57","slug":"alarmante-el-numero-de-feminicidios-en-veracruz-veronica-pulido","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/04\/29\/alarmante-el-numero-de-feminicidios-en-veracruz-veronica-pulido\/","title":{"rendered":"Alarmante el n\u00famero de feminicidios en Veracruz: Ver\u00f3nica Pulido"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Cada que en M\u00e9xico y en espec\u00edfico Veracruz, se habla de cifras, n\u00fameros y estad\u00edsticas de la violencia en contra de las mujeres, es fundamental tener presente que se est\u00e1 hablando tambi\u00e9n de hermanas, madres e hijas, de v\u00edctimas que tienen nombre y rostro, de familias que nunca volver\u00e1n a estar completas, puntualiz\u00f3 la diputada local, Ver\u00f3nica Pulido Herrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> En ese sentido, expuso que las cifras del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica report\u00f3 que, el estado de Veracruz tuvo 19 feminicidios al cierre del mes de marzo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> &#8220;El gobernador debe evitar acusar nuevamente a los medios de comunicaci\u00f3n de sensacionalistas, pues si bien la muerte de Mar\u00eda Jos\u00e9 en Perote ya fue confirmada como suicidio; para abril ya se contabilizan 21 feminicidios, n\u00fameros alarmantes en tan solo 4 meses del a\u00f1o&#8221;. <\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;\u00bfDe qu\u00e9 sirve dar una conferencia de prensa informando que ya hay avances en diversas investigaciones?, si no existe una titular del Instituto Veracruzano de las Mujeres, quien es la responsable de que se dise\u00f1en pol\u00edticas p\u00fablicas transversales con perspectiva de g\u00e9nero, y estrategias prevenir la violencia en raz\u00f3n de g\u00e9nero. La \u00a0la figura de encargada de despacho no existe en la ley&#8221;, sentenci\u00f3. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">De la misma manera, Ver\u00f3nica Pulido detall\u00f3 que, los datos de la Encuesta Nacional de Victimizaci\u00f3n y Percepci\u00f3n sobre Seguridad P\u00fablica (ENVIPE) 2022 presentada por el el INEGI, se\u00f1ala que en Veracruz, a m\u00e1s del 50 por ciento de las carpetas de investigaci\u00f3n por violencia contra las mujeres, se les da &#8220;carpetazo&#8221; y se olvidan.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> &#8220;Las mujeres en Veracruz no est\u00e1n solas; vamos a seguir pugnando por que haya un acceso r\u00e1pido, eficaz y transparente, para que accedan a su derecho humano a la justicia y \u00a0que las autoridades \u00a0brinden la atenci\u00f3n y acompa\u00f1amiento respectivo \u00a0a las v\u00edctimas de violencia de g\u00e9nero&#8221;, culmin\u00f3.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Cada que en M\u00e9xico y en espec\u00edfico Veracruz, se habla de cifras, n\u00fameros y estad\u00edsticas de la violencia en contra de las mujeres, es fundamental tener presente que se est\u00e1 hablando tambi\u00e9n de hermanas, madres e hijas, de v\u00edctimas que tienen nombre y rostro, de familias que nunca volver\u00e1n a [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":35003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[13540,202,180,21561],"class_list":["post-104935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-alarmante","tag-feminicidios","tag-veracruz","tag-veronica-pulido-herrera","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/104935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=104935"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/104935\/revisions"}],"predecessor-version":[{"id":104936,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/104935\/revisions\/104936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/35003"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=104935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=104935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=104935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}